{"id":7928,"date":"2024-11-29T10:26:15","date_gmt":"2024-11-29T03:26:15","guid":{"rendered":"https:\/\/noethera.com\/?p=7928"},"modified":"2024-11-29T10:26:17","modified_gmt":"2024-11-29T03:26:17","slug":"the-ultimate-guide-to-optimizing-your-website-budget-without-overpaying","status":"publish","type":"post","link":"https:\/\/noethera.com\/id\/insight\/the-ultimate-guide-to-optimizing-your-website-budget-without-overpaying\/","title":{"rendered":"Cara Menentukan &amp; Optimalkan Budget Pembuatan Website"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div>\n<div class=\"wp-block-uagb-container uagb-block-kqaadqdx alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-6959b097 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><\/div><p class=\"uagb-ifb-desc\">Punya website yang profesional itu udah jadi investasi wajib buat bisnis di era digital. Website ibarat toko online kamu\u2014tempat buat ningkatin kredibilitas dan alat buat berinteraksi sama pelanggan. Mau bisnis kamu masih kecil atau udah skala besar, punya website yang fungsional dan menarik itu bukan lagi pilihan, tapi kebutuhan.<br><br>Tapi, salah satu tantangan terbesar buat bisnis adalah: berapa sih budget yang pas buat bikin website? Dengan banyaknya pilihan, dari freelancer murah sampai digital agency kelas atas, harga bisa berkisar dari ratusan ribu sampai puluhan juta rupiah. Gimana caranya supaya kamu gak overbudget tapi tetap dapet website yang sesuai kebutuhan bisnis kamu? Panduan ini bakal ngebantu kamu optimalkan budget website tanpa ngorbanin kualitas.<\/p><\/div><\/div>\n\n\n\t\t\t\t<div class=\"wp-block-uagb-table-of-contents uagb-toc__align-left uagb-toc__columns-1  uagb-block-498bbe02\"\n\t\t\t\t\tdata-scroll= \"1\"\n\t\t\t\t\tdata-offset= \"30\"\n\t\t\t\t\tstyle=\"\"\n\t\t\t\t>\n\t\t\t\t<div class=\"uagb-toc__wrap\">\n\t\t\t\t\t\t<div class=\"uagb-toc__title\">\n\t\t\t\t\t\t\tDaftar Isi\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uagb-toc__list-wrap\">\n\t\t\t\t\t\t<ol class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#why-having-a-website-is-crucial-for-your-business\" class=\"uagb-toc-link__trigger\">Kenapa Punya Website Itu Penting Buat Bisnis Kamu<\/a><li class=\"uagb-toc__list\"><a href=\"#factors-influencing-website-development-costs\" class=\"uagb-toc-link__trigger\">Faktor yang Mempengaruhi Biaya Pembuatan Website<\/a><li class=\"uagb-toc__list\"><a href=\"#how-to-optimize-your-website-budget\" class=\"uagb-toc-link__trigger\">Cara Optimalkan Budget Website Kamu<\/a><li class=\"uagb-toc__list\"><a href=\"#common-mistakes-to-avoid\" class=\"uagb-toc-link__trigger\">Kesalahan Umum yang Harus Dihindari<\/a><li class=\"uagb-toc__list\"><a href=\"#tips-for-negotiating-with-digital-agencies\" class=\"uagb-toc-link__trigger\">Tips Negosiasi Sama Agensi Digital<\/a><li class=\"uagb-toc__list\"><a href=\"#why-choosing-the-right-agency-matters\" class=\"uagb-toc-link__trigger\">Kenapa Pilih Agensi yang Tepat Itu Penting<\/a><li class=\"uagb-toc__list\"><a href=\"#conclusion\" class=\"uagb-toc-link__trigger\">Kesimpulan<\/a><\/ol>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-18056ce0 uagb-infobox__content-wrap  uagb-infobox-icon-below-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h1 class=\"uagb-ifb-title\">Kenapa Punya Website Itu Penting Buat Bisnis Kamu<\/h1><\/div><p class=\"uagb-ifb-desc\">Website itu aset digital paling berharga buat bisnis kamu. Biasanya, website jadi tempat pertama pelanggan ngelihat brand kamu, jadi ini berperan besar dalam ngebangun kesan pertama. Kalau websitenya rapi dan profesional, mereka bakal percaya sama bisnis kamu. Tapi kalau asal-asalan, peluang bisa langsung hilang.<br><br>Di tengah kompetisi pasar yang ketat, bisnis tanpa website bisa kehilangan kredibilitas dan kesempatan jualan. Selain itu, website juga jadi alat marketing yang efektif. Kamu bisa pamerin produk atau layanan, tarik pelanggan baru, dan bangun hubungan jangka panjang.<br><br>Buat bisnis e-commerce, website adalah fondasi buat menghasilkan pendapatan. Sementara buat bisnis layanan, website jadi tempat dapetin leads atau prospek baru. Intinya, website itu bukan cuma soal relevansi, tapi juga alat buat bikin bisnis kamu terus berkembang. Tapi ya, kualitas website itu penting banget, dan di sinilah budget yang tepat berperan besar.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-c6fec501 uagb-infobox__content-wrap  uagb-infobox-icon-below-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h1 class=\"uagb-ifb-title\"><strong>Faktor yang Mempengaruhi Biaya Pembuatan Website<\/strong><\/h1><\/div><p class=\"uagb-ifb-desc\">Beberapa faktor bakal nentuin berapa besar biaya buat bikin website. Kalau kamu paham elemen-elemen ini, kamu bisa bikin keputusan lebih bijak dan hindari pengeluaran yang gak perlu.<\/p><\/div><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li style=\"padding-top:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20)\"><strong>Jenis Website<\/strong><br>Jenis website yang kamu butuhin bakal langsung ngaruh ke harga. Website company profile yang basic, biasanya cuma ada homepage, halaman \"Tentang Kami,\" dan form kontak, biayanya relatif terjangkau. Sebaliknya, website e-commerce butuh fitur canggih kayak shopping cart, pembayaran online, dan manajemen stok. Fitur-fitur ini butuh waktu dan keahlian lebih, yang bikin biayanya lebih mahal. Website dinamis seperti web app dengan fitur interaktif kayak akun pengguna atau real-time updates harganya bisa lebih tinggi lagi.<\/li>\n\n\n\n<li style=\"padding-top:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20)\"><strong>Fitur dan Fungsionalitas<\/strong><br>Setiap fitur tambahan bakal nambah biaya pengembangan. Misalnya, integrasi sistem booking, live chat, atau tools SEO butuh waktu dan skill lebih buat dikembangin. Daripada fokus masukin semua fitur, pastiin kamu cuma ambil yang bener-bener dibutuhin bisnis kamu.<\/li>\n\n\n\n<li style=\"padding-top:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20)\"><strong>Desain: Custom atau Template<\/strong><br>Desain custom yang disesuaikan sama identitas brand kamu bisa bikin website kelihatan profesional dan unik. Ini juga ningkatin pengalaman pengguna (UX) dan bikin bisnis kamu beda dari kompetitor. Tapi, custom desain lebih mahal dibanding pake template yang lebih cepat dan murah buat diimplementasi, walaupun gak sefleksibel atau seunik desain custom.<\/li>\n\n\n\n<li style=\"padding-top:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20)\"><strong>Pengalaman Agensi Digital<\/strong><br>Reputasi dan pengalaman agensi atau developer yang kamu pilih juga ngaruh ke harga. Agensi yang udah terbukti pengalaman biasanya lebih mahal karena mereka punya sumber daya dan track record yang jelas. Freelancer atau agensi kecil mungkin lebih murah, tapi kualitasnya bisa gak konsisten.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-9021c5fa uagb-infobox__content-wrap  uagb-infobox-icon-below-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h1 class=\"uagb-ifb-title\"><strong>Cara Optimalkan Budget Website Kamu<\/strong><\/h1><\/div><p class=\"uagb-ifb-desc\">Biar investasi kamu gak sia-sia, penting buat optimalkan budget website dengan efektif. Ini soal nyesuaiin kebutuhan bisnis kamu dengan kondisi finansial.<br><br>Mulai dari tentuin tujuan website kamu. Apakah website ini buat naikin penjualan, dapetin leads, atau sekedar bikin eksistensi online? Tujuan ini bakal nentuin fitur yang kamu butuhin, yang secara langsung ngaruh ke biaya pengembangan. Misalnya, coffee shop lokal mungkin cuma butuh website sederhana dengan menu dan form kontak, sementara retailer nasional butuh platform e-commerce yang kompleks.<br><br>Lanjut dengan riset beberapa agensi atau developer. Minta penawaran harga, bandingin portofolio mereka, dan baca ulasan dari klien sebelumnya. Jangan langsung pilih yang paling murah. Fokus ke value yang kamu dapet, kayak kualitas, skalabilitas, dan dukungan jangka panjang. Kadang, biaya awal yang lebih tinggi bisa ngasih hasil lebih baik dibanding solusi murah yang butuh perbaikan terus-menerus.<br><br>Terakhir, pikirin juga biaya jangka panjang. Website itu bukan investasi sekali bayar. Kamu perlu siapin budget buat perpanjangan domain, hosting, maintenance, dan pembaruan. Ini sering dilupakan, padahal penting banget buat jaga website tetap aman dan berfungsi optimal.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-697e79f9 uagb-infobox__content-wrap  uagb-infobox-icon-below-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h1 class=\"uagb-ifb-title\">Kesalahan Umum yang Harus Dihindari<\/h1><\/div><p class=\"uagb-ifb-desc\">Waktu nyusun budget website, gampang banget buat bikin kesalahan yang bikin biaya membengkak atau hasilnya malah jelek. Ini beberapa hal yang mesti kamu hindari:<\/p><\/div><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li style=\"padding-top:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20)\"><strong>Pilih yang Termurah<\/strong><br>Murah emang menggoda, tapi seringkali ada kompromi di kualitas, fungsionalitas, atau dukungan jangka panjang. Website yang desainnya jelek bisa bikin brand kamu keliatan gak profesional, dan perbaikannya bisa makan biaya besar di masa depan.<\/li>\n\n\n\n<li style=\"padding-top:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20)\"><strong>Lupa Biaya Jangka Panjang<\/strong><br>Banyak bisnis lupa masukin biaya hosting, maintenance, dan update ke rencana budget mereka. Padahal, ini penting banget buat jaga keamanan dan performa website kamu.<\/li>\n\n\n\n<li style=\"padding-top:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20)\"><strong>Terlalu Fokus ke Tren<\/strong><br>Fitur atau animasi yang lagi tren kadang keliatan keren, tapi bisa aja gak relevan buat bisnis kamu. Prioritasin fungsi dan pengalaman pengguna dibanding cuma estetika.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-aba46c23 uagb-infobox__content-wrap  uagb-infobox-icon-below-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h1 class=\"uagb-ifb-title\">Tips Negosiasi Sama Agensi Digital<\/h1><\/div><p class=\"uagb-ifb-desc\">Negosiasi sama agensi bisa terasa menantang, tapi penting banget buat pastiin kamu dapet value terbaik dari budget kamu. Mulai dengan bikin brief proyek yang jelas dan detail. Ini bakal bantu agensi ngerti tujuan dan kebutuhan kamu, jadi mereka bisa kasih penawaran yang akurat.<br><br>Jangan ragu buat tanya soal pengalaman mereka, proses kerja, dan apa aja yang termasuk di harga mereka. Kalau biayanya keliatan tinggi, minta rincian buat tau alokasinya ke mana. Terbuka soal budget itu penting, tapi pastiin juga ekspektasi kamu sesuai sama kualitas yang kamu harapkan.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-e219a5cf uagb-infobox__content-wrap  uagb-infobox-icon-below-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h1 class=\"uagb-ifb-title\">Kenapa Pilih Agensi yang Tepat Itu Penting<\/h1><\/div><p class=\"uagb-ifb-desc\">Agensi yang tepat bakal jadi faktor besar buat kesuksesan website kamu. Mereka gak cuma bikin website yang berfungsi, tapi juga bikin platform yang sesuai sama brand kamu, engaging buat audiens, dan mendorong pertumbuhan bisnis.<br><br>Di <strong>Noethera<\/strong>, kami paham kalau tiap bisnis itu unik. Makanya, kami nawarin solusi custom yang dirancang buat ngasih value maksimal. Layanan kami mulai dari desain custom sampai dukungan jangka panjang, biar website kamu selalu relevan dan efektif.<\/p><\/div><\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-cb79a504 uagb-infobox__content-wrap  uagb-infobox-icon-below-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h1 class=\"uagb-ifb-title\">Kesimpulan<\/h1><\/div><p class=\"uagb-ifb-desc\">Optimalkan budget website itu butuh pemahaman jelas soal tujuan bisnis, perencanaan yang matang, dan kerja bareng agensi yang pas. Dengan fokus ke fitur penting, hindari kesalahan umum, dan negosiasi yang efektif, kamu bisa dapet website berkualitas tanpa overbudget.<br><br>Kalau kamu siap buat bikin website yang sesuai dengan tujuan bisnis tanpa boros, hubungi <strong>Noethera<\/strong> sekarang juga buat konsultasi gratis. Yuk, wujudkan visi bisnis kamu dan bikin website yang bikin bisnis kamu bersinar di dunia digital!<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-a560df08\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:60%\">\n<div data-aos= \"fade\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-social-share uagb-social-share__outer-wrap uagb-social-share__layout-horizontal uagb-block-c0e7f988\">\n<div class=\"wp-block-uagb-social-share-child uagb-ss-repeater uagb-ss__wrapper uagb-block-1cc948e8\"><span class=\"uagb-ss__link\" data-href=\"https:\/\/www.facebook.com\/sharer.php?u=\" tabindex=\"0\" role=\"button\" aria-label=\"facebook\"><span class=\"uagb-ss__source-wrap\"><span class=\"uagb-ss__source-icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.8 90.69 226.4 209.3 245V327.7h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.3 482.4 504 379.8 504 256z\"><\/path><\/svg><\/span><\/span><\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-social-share-child uagb-ss-repeater uagb-ss__wrapper uagb-block-7005fafb\"><span class=\"uagb-ss__link\" data-href=\"https:\/\/twitter.com\/share?url=\" tabindex=\"0\" role=\"button\" aria-label=\"twitter\"><span class=\"uagb-ss__source-wrap\"><span class=\"uagb-ss__source-icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M400 32H48C21.5 32 0 53.5 0 80v352c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V80c0-26.5-21.5-48-48-48zm-48.9 158.8c.2 2.8 .2 5.7 .2 8.5 0 86.7-66 186.6-186.6 186.6-37.2 0-71.7-10.8-100.7-29.4 5.3 .6 10.4 .8 15.8 .8 30.7 0 58.9-10.4 81.4-28-28.8-.6-53-19.5-61.3-45.5 10.1 1.5 19.2 1.5 29.6-1.2-30-6.1-52.5-32.5-52.5-64.4v-.8c8.7 4.9 18.9 7.9 29.6 8.3a65.45 65.45 0 0 1 -29.2-54.6c0-12.2 3.2-23.4 8.9-33.1 32.3 39.8 80.8 65.8 135.2 68.6-9.3-44.5 24-80.6 64-80.6 18.9 0 35.9 7.9 47.9 20.7 14.8-2.8 29-8.3 41.6-15.8-4.9 15.2-15.2 28-28.8 36.1 13.2-1.4 26-5.1 37.8-10.2-8.9 13.1-20.1 24.7-32.9 34z\"><\/path><\/svg><\/span><\/span><\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-social-share-child uagb-ss-repeater uagb-ss__wrapper uagb-block-bc1ecbcf\"><span class=\"uagb-ss__link\" data-href=\"https:\/\/pinterest.com\/pin\/create\/link\/?url=\" tabindex=\"0\" role=\"button\" aria-label=\"pinterest\"><span class=\"uagb-ss__source-wrap\"><span class=\"uagb-ss__source-icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M448 80v352c0 26.5-21.5 48-48 48H154.4c9.8-16.4 22.4-40 27.4-59.3 3-11.5 15.3-58.4 15.3-58.4 8 15.3 31.4 28.2 56.3 28.2 74.1 0 127.4-68.1 127.4-152.7 0-81.1-66.2-141.8-151.4-141.8-106 0-162.2 71.1-162.2 148.6 0 36 19.2 80.8 49.8 95.1 4.7 2.2 7.1 1.2 8.2-3.3 .8-3.4 5-20.1 6.8-27.8 .6-2.5 .3-4.6-1.7-7-10.1-12.3-18.3-34.9-18.3-56 0-54.2 41-106.6 110.9-106.6 60.3 0 102.6 41.1 102.6 99.9 0 66.4-33.5 112.4-77.2 112.4-24.1 0-42.1-19.9-36.4-44.4 6.9-29.2 20.3-60.7 20.3-81.8 0-53-75.5-45.7-75.5 25 0 21.7 7.3 36.5 7.3 36.5-31.4 132.8-36.1 134.5-29.6 192.6l2.2 .8H48c-26.5 0-48-21.5-48-48V80c0-26.5 21.5-48 48-48h352c26.5 0 48 21.5 48 48z\"><\/path><\/svg><\/span><\/span><\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-social-share-child uagb-ss-repeater uagb-ss__wrapper uagb-block-00c1f9d7\"><span class=\"uagb-ss__link\" data-href=\"https:\/\/www.linkedin.com\/shareArticle?url=\" tabindex=\"0\" role=\"button\" aria-label=\"linkedin\"><span class=\"uagb-ss__source-wrap\"><span class=\"uagb-ss__source-icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg><\/span><\/span><\/span><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-marketing-button uagb-marketing-btn__align-full uagb-marketing-btn__align-text-center uagb-marketing-btn__icon-after uagb-block-a8312775 wp-block-button\"><a href=\"https:\/\/wa.me\/message\/VCJXXER4RXMLB1\" class=\"uagb-marketing-btn__link wp-block-button__link\" target=\"_blank\" rel=\"noopener noreferrer\"><span class=\"uagb-marketing-btn__title\">START YOUR PROJECT<\/span><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M256 0C114.6 0 0 114.6 0 256c0 141.4 114.6 256 256 256s256-114.6 256-256C512 114.6 397.4 0 256 0zM406.6 278.6l-103.1 103.1c-12.5 12.5-32.75 12.5-45.25 0s-12.5-32.75 0-45.25L306.8 288H128C110.3 288 96 273.7 96 256s14.31-32 32-32h178.8l-49.38-49.38c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l103.1 103.1C414.6 241.3 416 251.1 416 256C416 260.9 414.6 270.7 406.6 278.6z\"><\/path><\/svg><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Learn how to optimize your website budget without overpaying. Get practical tips to balance cost, quality, and business needs for maximum value.<\/p>","protected":false},"author":1,"featured_media":7931,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[117,8],"tags":[],"class_list":["post-7928","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tips","category-website-development"],"aioseo_notices":[],"spectra_custom_meta":{"_edit_lock":["1732851996:1"],"_uag_custom_page_level_css":[""],"_monsterinsights_skip_tracking":[""],"_monsterinsights_sitenote_active":[""],"_uf_show_specific_survey":["0"],"_uf_disable_surveys":[""],"ast-site-content-layout":["default"],"theme-transparent-header-meta":[""],"adv-header-id-meta":[""],"stick-header-meta":[""],"astra-migrate-meta-layouts":["set"],"footnotes":[""],"_edit_last":["1"],"_aioseo_title":[null],"_aioseo_description":[null],"_aioseo_keywords":["a:0:{}"],"_aioseo_og_title":[null],"_aioseo_og_description":[null],"_aioseo_og_article_section":[""],"_aioseo_og_article_tags":["a:0:{}"],"_aioseo_twitter_title":[null],"_aioseo_twitter_description":[null],"site-post-title":[""],"_wp_desired_post_slug":["bagaimana-cara-mencari-pendanaan-atau-fundraising-untuk-usaha-kecil-2"],"site-content-style":["default"],"_wp_old_date":["2024-07-26"],"om_disable_all_campaigns":[""],"_wp_old_slug":["check-hal-ini-saat-gunakan-jasa-pembuatan-website-properti-di-lombok"],"_oembed_ebd83306991f66e5702e699930f9ff70":["<iframe title=\"THE BUCKET SHOT\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/r25IWquxe9s?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>"],"_oembed_time_ebd83306991f66e5702e699930f9ff70":["1728155670"],"_oembed_4d96f25fe6d309c24390952d032a7e27":["<iframe title=\"THE BUCKET SHOT\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/r25IWquxe9s?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>"],"_oembed_time_4d96f25fe6d309c24390952d032a7e27":["1728155961"],"_themeisle_gutenberg_block_has_review":[""],"_thumbnail_id":["7931"],"_oembed_30b82d72f01950da222a3502f097edc4":["<iframe title=\"Lexus Car Dealership \u2013  FPV Drone Fly Through\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/qkc7IlqlHRc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>"],"_oembed_time_30b82d72f01950da222a3502f097edc4":["1730542994"],"_oembed_7255d9109771c184a532580941b2744a":["<iframe title=\"Lexus Car Dealership \u2013  FPV Drone Fly Through\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/qkc7IlqlHRc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>"],"_oembed_time_7255d9109771c184a532580941b2744a":["1730542997"],"_uagb_toc_options":["a:2:{s:17:\"_uagb_toc_version\";s:10:\"1778499543\";s:18:\"_uagb_toc_headings\";a:7:{i:0;a:4:{s:5:\"level\";i:1;s:2:\"id\";s:49:\"why-having-a-website-is-crucial-for-your-business\";s:7:\"content\";s:49:\"Why Having a Website is Crucial for Your Business\";s:5:\"depth\";i:1;}i:1;a:4:{s:5:\"level\";i:1;s:2:\"id\";s:45:\"factors-influencing-website-development-costs\";s:7:\"content\";s:45:\"Factors Influencing Website Development Costs\";s:5:\"depth\";i:1;}i:2;a:4:{s:5:\"level\";i:1;s:2:\"id\";s:35:\"how-to-optimize-your-website-budget\";s:7:\"content\";s:35:\"How to Optimize Your Website Budget\";s:5:\"depth\";i:1;}i:3;a:4:{s:5:\"level\";i:1;s:2:\"id\";s:24:\"common-mistakes-to-avoid\";s:7:\"content\";s:24:\"Common Mistakes to Avoid\";s:5:\"depth\";i:1;}i:4;a:4:{s:5:\"level\";i:1;s:2:\"id\";s:42:\"tips-for-negotiating-with-digital-agencies\";s:7:\"content\";s:42:\"Tips for Negotiating with Digital Agencies\";s:5:\"depth\";i:1;}i:5;a:4:{s:5:\"level\";i:1;s:2:\"id\";s:37:\"why-choosing-the-right-agency-matters\";s:7:\"content\";s:37:\"Why Choosing the Right Agency Matters\";s:5:\"depth\";i:1;}i:6;a:4:{s:5:\"level\";i:1;s:2:\"id\";s:10:\"conclusion\";s:7:\"content\";s:10:\"Conclusion\";s:5:\"depth\";i:1;}}}"],"_uag_page_assets":["a:9:{s:3:\"css\";s:238623:\"\/* vietnamese *\/\n@font-face {\n  font-family: 'League Spartan';\n  font-style: normal;\n  font-weight: 400;\n  font-display: fallback;\n  src: url(https:\/\/noethera.com\/wp-content\/uploads\/uag-plugin\/assets\/fonts\/league-spartan\/kJEnBuEW6A0lliaV_m88ja5Twtx8BWhtkDVmjZvM_oTZDM1dJgs.woff2) format('woff2');\n  unicode-range: U+0102-0103, U+0110-0111, U+0128-0129, U+0168-0169, U+01A0-01A1, U+01AF-01B0, U+0300-0301, U+0303-0304, U+0308-0309, U+0323, U+0329, U+1EA0-1EF9, U+20AB;\n}\n\/* latin-ext *\/\n@font-face {\n  font-family: 'League Spartan';\n  font-style: normal;\n  font-weight: 400;\n  font-display: fallback;\n  src: url(https:\/\/noethera.com\/wp-content\/uploads\/uag-plugin\/assets\/fonts\/league-spartan\/kJEnBuEW6A0lliaV_m88ja5Twtx8BWhtkDVmjZvM_oTZDc1dJgs.woff2) format('woff2');\n  unicode-range: U+0100-02BA, U+02BD-02C5, U+02C7-02CC, U+02CE-02D7, U+02DD-02FF, U+0304, U+0308, U+0329, U+1D00-1DBF, U+1E00-1E9F, U+1EF2-1EFF, U+2020, U+20A0-20AB, U+20AD-20C0, U+2113, U+2C60-2C7F, U+A720-A7FF;\n}\n\/* latin *\/\n@font-face {\n  font-family: 'League Spartan';\n  font-style: normal;\n  font-weight: 400;\n  font-display: fallback;\n  src: url(https:\/\/noethera.com\/wp-content\/uploads\/uag-plugin\/assets\/fonts\/league-spartan\/kJEnBuEW6A0lliaV_m88ja5Twtx8BWhtkDVmjZvM_oTZA81d.woff2) format('woff2');\n  unicode-range: U+0000-00FF, U+0131, U+0152-0153, U+02BB-02BC, U+02C6, U+02DA, U+02DC, U+0304, U+0308, U+0329, U+2000-206F, U+20AC, U+2122, U+2191, U+2193, U+2212, U+2215, U+FEFF, U+FFFD;\n}\n.wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:0.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}\n.uagb-ifb-content>svg *{-webkit-transition:all 0.2s;-o-transition:all 0.2s;transition:all 0.2s}.uagb-ifb-content>svg,.uagb-ifb-content{display:inline-block}.uagb-ifb-content>svg{vertical-align:middle;width:inherit;height:inherit;font-style:initial}.uagb-ifb-content .uagb-ifb-icon-wrap svg{box-sizing:content-box;width:inherit;height:inherit}.uagb-ifb-button-wrapper:empty{display:none}div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link,div.uagb-ifb-cta a.uagb-infobox-cta-link,.entry .entry-content a.uagb-infobox-cta-link,a.uagb-infobox-link-wrap,.entry .entry-content a.uagb-infobox-link-wrap{text-decoration:none;align-items:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-middle .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-middle .uagb-ifb-content{-ms-flex-item-align:center;-webkit-align-self:center;align-self:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-image-valign-top .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-top .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-top .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-top .uagb-ifb-content{-webkit-align-self:self-start;align-self:self-start}.uagb-infobox-left{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-center{justify-content:center;text-align:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.uagb-infobox-right{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}.uagb-infobox-icon-above-title.uagb-infobox__content-wrap,.uagb-infobox-icon-below-title.uagb-infobox__content-wrap{display:block;width:100%}.uagb-infobox-icon-left-title .uagb-ifb-content>svg,.uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:10px}.uagb-infobox-icon-right-title .uagb-ifb-content>svg,.uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:10px}.uagb-infobox-icon-left.uagb-infobox__content-wrap,.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:-webkit-flex;display:-moz-box;display:flex;-js-display:flex}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-image-content,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-image-content,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{flex-shrink:0;line-height:0}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-left .uagb-ifb-content,.uagb-infobox-icon-right .uagb-ifb-content{flex-grow:1}.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}.uagb-ifb-content img{position:relative;display:inline-block;line-height:0;width:auto;height:auto !important;max-width:100%;border-radius:inherit;-webkit-box-sizing:content-box;-moz-box-sizing:content-box;-webkit-border-radius:inherit}.uagb-infobox-module-link{position:absolute;top:0;right:0;bottom:0;left:0;z-index:4;width:100%;height:100%}.uagb-edit-mode .uagb-infobox-module-link{z-index:2}.uagb-infobox-link-icon-after{margin-right:0;margin-left:5px}.uagb-infobox-link-icon-before{margin-right:5px;margin-left:0}.uagb-infobox-link-icon{-webkit-transition:all 200ms linear;transition:all 200ms linear}.uagb-infobox__content-wrap{box-sizing:border-box;position:relative;width:100%;word-break:break-word;z-index:1}.uagb-ifb-separator{display:inline-block;margin:0;border-top-color:#333;border-top-style:solid;border-top-width:2px;line-height:0}.uagb-ifb-button-wrapper{line-height:1}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link{background-color:unset;border:none}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link:hover{background-color:unset;border-color:unset}.uagb-ifb-button-wrapper .uagb-infobox-cta-link{cursor:pointer}.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{width:auto}.uagb-ifb-button-wrapper .wp-block-button__link svg,.uagb-ifb-button-wrapper .ast-outline-button svg{fill:currentColor}.uagb-infobox__content-wrap a{-webkit-box-shadow:none;box-shadow:none;text-decoration:none}.uagb-ifb-title-wrap{width:100%}.uagb-ifb-title{margin-block-start:0}.uagb-ifb-title-wrap .uagb-ifb-title-prefix{display:block;padding:0;margin:0}.uagb-infobox__content-wrap.uagb-infobox__content-wrap{position:relative}.uagb-ifb-content{width:100%}.uagb-infobox__content-wrap.uagb-infobox,.uagb-ifb-content,.uagb-ifb-title-wrap,.uagb-ifb-title-prefix *,svg.dashicon.dashicons-upload{z-index:1}a.uagb-infobox-link-wrap{color:inherit}.uagb-ifb-content p:empty{display:none}.uagb-infobox__content-wrap .uagb-ifb-content img{display:inline-block;max-width:100%}.uagb-infobox__content-wrap .uagb-ifb-content svg{display:inline-block}.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{box-sizing:content-box}.uagb-infobox-cta-link>svg{vertical-align:middle;width:15px;height:15px;font-size:15px}.uagb-infobox-cta-link{display:inline-flex}.block-editor-page #wpwrap .uagb-infobox-cta-link svg,.uagb-infobox-cta-link svg{font-style:normal}.uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}.uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=\"rtl\"] .uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,html[dir=\"rtl\"] .uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=\"rtl\"] .uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,html[dir=\"rtl\"] .uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}html[dir=\"rtl\"] .uagb-infobox-left{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}html[dir=\"rtl\"] .uagb-infobox-right{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-icon-left .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:flex}.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}a.uagb-infbox__link-to-all{position:absolute;top:0;left:0;z-index:3;width:100%;height:100%;box-shadow:none;text-decoration:none;-webkit-box-shadow:none}@media only screen and (max-width: 976px){.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{padding:0;margin-bottom:20px}.uagb-infobox-stacked-tablet.uagb-reverse-order-tablet.uagb-infobox__content-wrap{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-content,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{display:block;width:100%;text-align:center}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{margin-right:0;margin-left:0}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}@media screen and (max-width: 767px){.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap{padding:0;margin-bottom:20px;margin-right:0;margin-left:0}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap.uagb-reverse-order-mobile{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-content{display:block;width:100%;text-align:center}.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}.uagb-ifb-icon svg{width:inherit;height:inherit;vertical-align:middle}.uagb-ifb-button-icon{height:15px;width:15px;font-size:15px;vertical-align:middle}.uagb-ifb-button-icon svg{height:inherit;width:inherit;display:inline-block}.uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:right}.uagb-ifb-cta-button{display:inline-block}.uagb-disable-link{pointer-events:none}@media only screen and (min-width: 977px){.uagb-infobox-margin-wrapper{display:flex}}.uagb-ifb-content .uagb-ifb-desc p:last-child{margin-bottom:0}\n.wp-block-uagb-table-of-contents .uagb-toc__wrap{display:inline-block;max-width:-moz-available;max-width:-webkit-fill-available;max-width:fill-available}.wp-block-uagb-table-of-contents li.uagb-toc__list{padding-top:10px}.wp-block-uagb-table-of-contents ul.uagb-toc__list,.wp-block-uagb-table-of-contents ol.uagb-toc__list{list-style-position:inside;padding-left:0;margin-bottom:0;margin-left:2.2em}.wp-block-uagb-table-of-contents ul.uagb-toc__list li,.wp-block-uagb-table-of-contents ol.uagb-toc__list li{margin:0}.wp-block-uagb-table-of-contents ul li:empty{display:none}.wp-block-uagb-table-of-contents .uagb-toc__title-wrap{display:flex;align-items:center}.wp-block-uagb-table-of-contents .uagb-toc__title{display:flex;align-items:center}.wp-block-uagb-table-of-contents .uagb-toc__is-collapsible.uagb-toc__title-wrap{cursor:pointer}.wp-block-uagb-table-of-contents .uag-toc__collapsible-wrap svg{width:20px;height:20px}.wp-block-uagb-table-of-contents svg{width:20px;height:20px;display:inline-block;margin-left:10px;cursor:pointer}.wp-block-uagb-table-of-contents .uag-toc__collapsible-wrap{display:flex;margin-left:10px;cursor:pointer}.wp-block-uagb-table-of-contents.uagb-toc__collapse .uagb-toc__list-wrap{display:none}.wp-block-uagb-table-of-contents.uagb-toc__collapse--list ul.uagb-toc__list,.wp-block-uagb-table-of-contents.uagb-toc__collapse--list ol.uagb-toc__list{padding-left:2px}ol.uagb-toc__list li.uagb-toc__list ul,ol.uagb-toc__list ul.uagb-toc__list ul{list-style-type:circle}ol.uagb-toc__list>ul,ol.uagb-toc__list>li{list-style-type:disc}.uagb-toc__scroll-top{position:fixed;right:50px;bottom:50px;display:none;padding:10px;background:#ccd0d4;cursor:pointer;font-size:1rem;line-height:1.85714285714286}.uagb-toc__scroll-top svg{width:1.6em;height:0.6em;margin-left:0;transform:translate(0, -20%) rotate(180deg);fill:currentColor}.uagb-toc__scroll-top.uagb-toc__show-scroll{display:inline-table}body[class*=\"astra\"] .uagb-toc__list{line-height:normal}.uagb-toc__list{margin-top:0}.wp-block-uagb-table-of-contents ol.uagb-toc__list li.uagb-toc__list.uagb-toc__list--expandable{list-style-type:none !important}ul.uagb-toc__list--child-of-closed-list{padding-top:0 !important}ul.uagb-toc__list--hidden-child{display:none !important}.list-open::before,.list-collapsed::before{content:\"\\25BC\" \/ \"\";transition:transform 0.3s ease;transform:scale(0.7) translateX(-50%);display:inline-block}.list-collapsed::before{transform:scale(0.7) rotate(-90deg) translate(-84%, 6%)}span.list-open,span.list-collapsed{cursor:pointer;outline:none !important}.uagb-toc__list.transition{transition:max-height 300ms ease-in-out, padding-top 300ms ease-in-out}.uagb-toc__loader{border:2px solid #f3f3f3;border-top:2px solid #0073aa;border-radius:50%;width:20px;height:20px;animation:spin 1.1s linear infinite;display:block;position:absolute;margin-top:5px}.uagb-toc__list-hidden{opacity:0}@keyframes spin{0%{transform:rotate(0deg)}100%{transform:rotate(360deg)}}[dir=\"rtl\"] .list-open::before{transform:scale(0.7) translateX(50%)}[dir=\"rtl\"] .list-collapsed::before{transform:scale(0.7) rotate(90deg) translate(84%, 6%)}[dir=\"rtl\"] .wp-block-uagb-table-of-contents.uagb-toc__collapse--list ul.uagb-toc__list,[dir=\"rtl\"] .wp-block-uagb-table-of-contents.uagb-toc__collapse--list ol.uagb-toc__list{padding-left:0;padding-right:2px;margin-left:0;margin-right:2.2em}\n.uagb-social-share__outer-wrap,.uagb-social-share__wrap{display:flex;align-items:center;justify-content:center}.uagb-social-share__layout-vertical.uagb-social-share__outer-wrap,.uagb-social-share__layout-vertical .uagb-social-share__wrap{flex-direction:column}.uagb-social-share__layout-vertical .wp-block-uagb-social-share-child.uagb-ss-repeater.uagb-ss__wrapper:first-child{margin-top:0 !important}.uagb-social-share__layout-vertical .wp-block-uagb-social-share-child.uagb-ss-repeater.uagb-ss__wrapper:last-child{margin-bottom:0 !important}.uagb-social-share__outer-wrap a.uagb-button__link:focus{box-shadow:none}.uagb-social-share__outer-wrap .uagb-ss__wrapper{padding:0;margin-left:5px;margin-right:5px;transition:all 0.2s;display:inline-flex;text-align:center}.uagb-social-share__outer-wrap .uagb-ss__source-wrap{display:inline-block}.uagb-social-share__outer-wrap .uagb-ss__link{color:#3a3a3a;display:inline-table;line-height:0;cursor:pointer}.uagb-social-share__outer-wrap .uagb-ss__source-icon{font-size:40px;width:40px;height:40px}.uagb-social-share__outer-wrap .uagb-ss__source-image{width:40px}@media (max-width: 976px){.uagb-social-share__layout-horizontal .uagb-ss__wrapper{margin-left:0;margin-right:0}}.uagb-social-share__layout-horizontal .wp-block-uagb-social-share-child.uagb-ss-repeater.uagb-ss__wrapper:first-child{margin-left:0 !important}.uagb-social-share__layout-horizontal .wp-block-uagb-social-share-child.uagb-ss-repeater.uagb-ss__wrapper:last-child{margin-right:0 !important}\n.wp-block-uagb-social-share .uagb-social-share__wrapper{text-decoration:none}.uagb-social-share__wrapper{box-shadow:none}.uagb-social-share__outer-wrap:not(.uagb-social-share__no-label) .uagb-social-share__source-wrap{margin-right:15px}.uagb-social-share__outer-wrap.uagb-social-share__icon-at-top .uagb-social-share__source-wrap{-ms-flex-item-align:flex-start;align-self:flex-start;margin-top:5px}\n.wp-block-uagb-marketing-button{display:-webkit-box;display:-ms-flexbox;display:flex}.wp-block-uagb-marketing-button p:empty{display:none}.wp-block-uagb-marketing-button .uagb-marketing-btn__title,.wp-block-uagb-marketing-button p.uagb-marketing-btn__prefix{margin-bottom:0}.wp-block-uagb-marketing-button .uagb-marketing-btn__link{z-index:1;display:inline-block;position:relative;-webkit-transition:all 0.2s;-o-transition:all 0.2s;transition:all 0.2s}.wp-block-uagb-marketing-button .uagb-marketing-btn__link.wp-block-button__link{width:auto}.wp-block-uagb-marketing-button svg{fill:currentColor;width:20px;height:20px;z-index:1;vertical-align:middle}.wp-block-uagb-marketing-button .uagb-marketing-btn__title,.wp-block-uagb-marketing-button svg{display:inline;vertical-align:middle}.wp-block-uagb-marketing-button.uagb-marketing-btn__align-center,.wp-block-uagb-marketing-button.uagb-marketing-btn__align-text-center .uagb-marketing-btn__title-wrap,.wp-block-uagb-marketing-button.uagb-marketing-btn__align-text-center .uagb-marketing-btn__link{-webkit-box-pack:center;-ms-flex-pack:center;justify-content:center;text-align:center}.wp-block-uagb-marketing-button.uagb-marketing-btn__align-left,.wp-block-uagb-marketing-button.uagb-marketing-btn__align-text-left .uagb-marketing-btn__title-wrap,.wp-block-uagb-marketing-button.uagb-marketing-btn__align-text-left .uagb-marketing-btn__link{-webkit-box-pack:start;-ms-flex-pack:start;justify-content:flex-start;text-align:left}.wp-block-uagb-marketing-button.uagb-marketing-btn__align-right,.wp-block-uagb-marketing-button.uagb-marketing-btn__align-text-right .uagb-marketing-btn__title-wrap,.wp-block-uagb-marketing-button.uagb-marketing-btn__align-text-right .uagb-marketing-btn__link{-webkit-box-pack:end;-ms-flex-pack:end;justify-content:flex-end;text-align:right}.wp-block-uagb-marketing-button.uagb-marketing-btn__align-full .uagb-marketing-btn__link{width:100%}.wp-block-uagb-marketing-button.uagb-marketing-btn__align-text-center .uagb-marketing-btn__prefix{text-align:center}.wp-block-uagb-marketing-button.uagb-marketing-btn__align-text-left .uagb-marketing-btn__prefix{text-align:left}.wp-block-uagb-marketing-button.uagb-marketing-btn__align-text-right .uagb-marketing-btn__prefix{text-align:right}.wp-block-uagb-marketing-button.uagb-marketing-btn__icon-after svg{order:2}.wp-block-uagb-marketing-button.uagb-marketing-btn__align-full .uagb-marketing-btn__wrap{width:100%}.wp-block-uagb-marketing-button.uagb-marketing-btn__align-center .uagb-marketing-btn__wrap,.wp-block-uagb-marketing-button.uagb-marketing-btn__align-text-center .uagb-marketing-btn__title-wrap{-webkit-box-pack:center;-ms-flex-pack:center;justify-content:center}.wp-block-uagb-marketing-button .uagb-marketing-btn__title-wrap{display:-webkit-box;display:-ms-flexbox;display:flex;-webkit-box-align:self-end;-ms-flex-align:self-end;align-items:self-end}.wp-block-uagb-marketing-button.uagb-marketing-btn__icon-after .uagb-marketing-btn__icon-wrap{order:2}.entry-content .wp-block-uagb-marketing-button .uagb-marketing-btn__link{text-decoration:none;display:inline-block}\n.wp-block-uagb-container.uagb-block-kqaadqdx .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-kqaadqdx .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-kqaadqdx .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-kqaadqdx .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-kqaadqdx .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-kqaadqdx{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-kqaadqdx > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: flex-start;flex-wrap: wrap;row-gap: 10px;column-gap: 48px;}.wp-block-uagb-container.uagb-block-kqaadqdx{box-shadow: 0px 0px   #00000070 ;padding-top: 40px;padding-bottom: 80px;padding-left: 100px;padding-right: 100px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: var(u002du002dast-global-color-5);;row-gap: 10px;column-gap: 48px;}.uagb-block-6959b097 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-6959b097 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-6959b097 .uagb-ifb-icon svg{fill: #333;}.uagb-block-6959b097.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-6959b097 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-6959b097 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6959b097.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6959b097.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6959b097 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-6959b097 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-6959b097 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6959b097 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-6959b097.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-6959b097.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-6959b097.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-6959b097.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-6959b097 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-6959b097.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-6959b097.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-6959b097 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-6959b097 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-6959b097 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-6959b097 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-6959b097.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-6959b097.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-6959b097 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-6959b097.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-6959b097.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-6959b097 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6959b097.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6959b097.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6959b097.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6959b097.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6959b097.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6959b097.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6959b097.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-6959b097.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-6959b097.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-498bbe02.wp-block-uagb-table-of-contents{text-align: left;}.uagb-block-498bbe02 .uagb-toc__list-wrap li a{color: #54595F;}.uagb-block-498bbe02 .uagb-toc__wrap .uagb-toc__title-wrap{justify-content: left;}.uagb-block-498bbe02 .uagb-toc__wrap .uagb-toc__title{justify-content: left;}.uagb-block-498bbe02 .uagb-toc__wrap{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-color: #333;border-style: solid;padding-left: 30px;padding-right: 30px;padding-top: 30px;padding-bottom: 30px;background: #fff;width: 100%;}.uagb-block-498bbe02 .uagb-toc__list-wrap{column-count: 1;overflow: hidden;text-align: left;}.uagb-block-498bbe02 .uagb-toc__list-wrap > ul.uagb-toc__list > li:first-child{padding-top: 0;}.uagb-block-498bbe02 .uagb-toc__list-wrap ul.uagb-toc__list:last-child > li:last-child{padding-bottom: 0;}.uagb-block-498bbe02 .uagb-toc__list .uagb-toc__list{list-style-type: disc !important;}.uagb-block-498bbe02 .uagb-toc__title{font-weight: Default;font-size: 20px;}.uagb-block-498bbe02 .uagb-toc__list-wrap ol li a{text-decoration: underline;}.uagb-block-18056ce0 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-18056ce0 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-18056ce0 .uagb-ifb-icon svg{fill: #333;}.uagb-block-18056ce0.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-18056ce0 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-18056ce0 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-18056ce0.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-18056ce0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-18056ce0 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-18056ce0 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-18056ce0 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-18056ce0 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-18056ce0.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-18056ce0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-18056ce0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-18056ce0.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-18056ce0 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-18056ce0.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 40px;margin-left: 0px;margin-right: 0px;}.uagb-block-18056ce0.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;}.uagb-block-18056ce0 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-18056ce0 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-18056ce0 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-18056ce0 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-18056ce0.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-18056ce0.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: border-box;}.uagb-block-18056ce0 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-18056ce0.uagb-infobox-icon-below-title{text-align: left;}.uagb-block-18056ce0 .uagb-ifb-content .uagb-ifb-image-content > img{width: 100%;box-sizing: border-box;}.uagb-block-18056ce0.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 100%;}.uagb-block-18056ce0 .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 100%;}.uagb-block-18056ce0 .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 100%;}.uagb-block-18056ce0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-18056ce0 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-18056ce0.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-18056ce0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-18056ce0.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-18056ce0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-18056ce0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-18056ce0.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-18056ce0.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-18056ce0.uagb-infobox-icon-below-title{text-align: right;}[dir=rtl] .uagb-block-18056ce0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-c6fec501 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-c6fec501 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-c6fec501 .uagb-ifb-icon svg{fill: #333;}.uagb-block-c6fec501.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c6fec501 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c6fec501 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-c6fec501.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-c6fec501.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-c6fec501 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c6fec501 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c6fec501 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-c6fec501 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-c6fec501.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-c6fec501.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-c6fec501.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-c6fec501.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-c6fec501 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-c6fec501.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 40px;margin-left: 0px;margin-right: 0px;}.uagb-block-c6fec501.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-c6fec501 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-c6fec501 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-c6fec501 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-c6fec501 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-c6fec501.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-c6fec501.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: border-box;}.uagb-block-c6fec501 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-c6fec501.uagb-infobox-icon-below-title{text-align: left;}.uagb-block-c6fec501 .uagb-ifb-content .uagb-ifb-image-content > img{width: 100%;box-sizing: border-box;}.uagb-block-c6fec501.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 100%;}.uagb-block-c6fec501 .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 100%;}.uagb-block-c6fec501 .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 100%;}.uagb-block-c6fec501.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-c6fec501 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c6fec501.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c6fec501.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c6fec501.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c6fec501.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c6fec501.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c6fec501.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c6fec501.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-c6fec501.uagb-infobox-icon-below-title{text-align: right;}[dir=rtl] .uagb-block-c6fec501.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-9021c5fa .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-9021c5fa .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-9021c5fa .uagb-ifb-icon svg{fill: #333;}.uagb-block-9021c5fa.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-9021c5fa .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-9021c5fa .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-9021c5fa.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-9021c5fa.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-9021c5fa .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-9021c5fa .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-9021c5fa .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-9021c5fa .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-9021c5fa.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-9021c5fa.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-9021c5fa.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-9021c5fa.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-9021c5fa .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-9021c5fa.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 40px;margin-left: 0px;margin-right: 0px;}.uagb-block-9021c5fa.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-9021c5fa .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-9021c5fa .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-9021c5fa .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-9021c5fa .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-9021c5fa.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-9021c5fa.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: border-box;}.uagb-block-9021c5fa .uagb-infobox__content-wrap{text-align: left;}.uagb-block-9021c5fa.uagb-infobox-icon-below-title{text-align: left;}.uagb-block-9021c5fa .uagb-ifb-content .uagb-ifb-image-content > img{width: 100%;box-sizing: border-box;}.uagb-block-9021c5fa.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 100%;}.uagb-block-9021c5fa .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 100%;}.uagb-block-9021c5fa .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 100%;}.uagb-block-9021c5fa.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-9021c5fa .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9021c5fa.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9021c5fa.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9021c5fa.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9021c5fa.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9021c5fa.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9021c5fa.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9021c5fa.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-9021c5fa.uagb-infobox-icon-below-title{text-align: right;}[dir=rtl] .uagb-block-9021c5fa.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-697e79f9 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-697e79f9 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-697e79f9 .uagb-ifb-icon svg{fill: #333;}.uagb-block-697e79f9.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-697e79f9 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-697e79f9 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-697e79f9.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-697e79f9.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-697e79f9 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-697e79f9 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-697e79f9 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-697e79f9 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-697e79f9.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-697e79f9.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-697e79f9.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-697e79f9.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-697e79f9 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-697e79f9.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 40px;margin-left: 0px;margin-right: 0px;}.uagb-block-697e79f9.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-697e79f9 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-697e79f9 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-697e79f9 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-697e79f9 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-697e79f9.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-697e79f9.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: border-box;}.uagb-block-697e79f9 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-697e79f9.uagb-infobox-icon-below-title{text-align: left;}.uagb-block-697e79f9 .uagb-ifb-content .uagb-ifb-image-content > img{width: 100%;box-sizing: border-box;}.uagb-block-697e79f9.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 100%;}.uagb-block-697e79f9 .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 100%;}.uagb-block-697e79f9 .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 100%;}.uagb-block-697e79f9.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-697e79f9 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-697e79f9.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-697e79f9.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-697e79f9.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-697e79f9.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-697e79f9.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-697e79f9.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-697e79f9.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-697e79f9.uagb-infobox-icon-below-title{text-align: right;}[dir=rtl] .uagb-block-697e79f9.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-aba46c23 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-aba46c23 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-aba46c23 .uagb-ifb-icon svg{fill: #333;}.uagb-block-aba46c23.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-aba46c23 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-aba46c23 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-aba46c23.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-aba46c23.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-aba46c23 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-aba46c23 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-aba46c23 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-aba46c23 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-aba46c23.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-aba46c23.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-aba46c23.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-aba46c23.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-aba46c23 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-aba46c23.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 40px;margin-left: 0px;margin-right: 0px;}.uagb-block-aba46c23.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-aba46c23 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-aba46c23 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-aba46c23 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-aba46c23 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-aba46c23.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-aba46c23.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: border-box;}.uagb-block-aba46c23 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-aba46c23.uagb-infobox-icon-below-title{text-align: left;}.uagb-block-aba46c23 .uagb-ifb-content .uagb-ifb-image-content > img{width: 100%;box-sizing: border-box;}.uagb-block-aba46c23.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 100%;}.uagb-block-aba46c23 .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 100%;}.uagb-block-aba46c23 .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 100%;}.uagb-block-aba46c23.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-aba46c23 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-aba46c23.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-aba46c23.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-aba46c23.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-aba46c23.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-aba46c23.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-aba46c23.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-aba46c23.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-aba46c23.uagb-infobox-icon-below-title{text-align: right;}[dir=rtl] .uagb-block-aba46c23.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-e219a5cf .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-e219a5cf .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-e219a5cf .uagb-ifb-icon svg{fill: #333;}.uagb-block-e219a5cf.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-e219a5cf .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-e219a5cf .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-e219a5cf.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-e219a5cf.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-e219a5cf .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-e219a5cf .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-e219a5cf .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-e219a5cf .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-e219a5cf.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-e219a5cf.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-e219a5cf.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-e219a5cf.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-e219a5cf .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-e219a5cf.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 40px;margin-left: 0px;margin-right: 0px;}.uagb-block-e219a5cf.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-e219a5cf .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-e219a5cf .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-e219a5cf .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-e219a5cf .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-e219a5cf.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-e219a5cf.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: border-box;}.uagb-block-e219a5cf .uagb-infobox__content-wrap{text-align: left;}.uagb-block-e219a5cf.uagb-infobox-icon-below-title{text-align: left;}.uagb-block-e219a5cf .uagb-ifb-content .uagb-ifb-image-content > img{width: 100%;box-sizing: border-box;}.uagb-block-e219a5cf.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 100%;}.uagb-block-e219a5cf .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 100%;}.uagb-block-e219a5cf .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 100%;}.uagb-block-e219a5cf.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-e219a5cf .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e219a5cf.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e219a5cf.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e219a5cf.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e219a5cf.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e219a5cf.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e219a5cf.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e219a5cf.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-e219a5cf.uagb-infobox-icon-below-title{text-align: right;}[dir=rtl] .uagb-block-e219a5cf.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-cb79a504 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-cb79a504 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-cb79a504 .uagb-ifb-icon svg{fill: #333;}.uagb-block-cb79a504.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-cb79a504 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-cb79a504 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-cb79a504.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-cb79a504.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-cb79a504 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-cb79a504 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-cb79a504 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-cb79a504 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-cb79a504.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-cb79a504.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-cb79a504.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-cb79a504.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-cb79a504 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-cb79a504.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 20px;margin-left: 0px;margin-right: 0px;}.uagb-block-cb79a504.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-cb79a504 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-cb79a504 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-cb79a504 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-cb79a504 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-cb79a504.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-cb79a504.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-cb79a504 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-cb79a504.uagb-infobox-icon-below-title{text-align: left;}.uagb-block-cb79a504.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-cb79a504 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-cb79a504.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-cb79a504.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-cb79a504.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-cb79a504.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-cb79a504.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-cb79a504.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-cb79a504.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-cb79a504.uagb-infobox-icon-below-title{text-align: right;}[dir=rtl] .uagb-block-cb79a504.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-a560df08 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a560df08 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a560df08 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a560df08 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a560df08 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a560df08{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a560df08 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-a560df08{box-shadow: 0px 0px   #00000070 ;padding-top: 30px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-c0e7f988 .uagb-ss-repeater span.uagb-ss__link{color: #3a3a3a;}.uagb-block-c0e7f988 .uagb-ss-repeater a.uagb-ss__link{color: #3a3a3a;}.uagb-block-c0e7f988 .uagb-ss-repeater span.uagb-ss__link svg{fill: #3a3a3a;}.uagb-block-c0e7f988 .uagb-ss-repeater a.uagb-ss__link svg{fill: #3a3a3a;}.uagb-block-c0e7f988.uagb-social-share__layout-vertical .uagb-ss__wrapper{margin-left: 0;margin-right: 0;margin-top: 5px;margin-bottom: 5px;}.uagb-block-c0e7f988.uagb-social-share__layout-vertical .uagb-ss__link{padding: 10px;}.uagb-block-c0e7f988.uagb-social-share__layout-horizontal .uagb-ss__link{padding: 10px;}.uagb-block-c0e7f988.uagb-social-share__layout-horizontal .uagb-ss__wrapper{margin-left: 5px;margin-right: 5px;}.uagb-block-c0e7f988 .wp-block-uagb-social-share-child {border-radius: 0px;}.uagb-block-c0e7f988 .uagb-ss__source-wrap{width: 30px;}.uagb-block-c0e7f988 .uagb-ss__source-wrap svg{width: 30px;height: 30px;}.uagb-block-c0e7f988 .uagb-ss__source-image{width: 30px;}.uagb-block-c0e7f988 .uagb-ss__source-icon{width: 30px;height: 30px;font-size: 30px;}.uagb-block-c0e7f988.uagb-social-share__outer-wrap{justify-content: flex-start;-webkit-box-pack: flex-start;-ms-flex-pack: flex-start;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.uagb-block-a8312775 .uagb-marketing-btn__prefix{font-size: 13px;line-height: 2em;margin-top: 0px;}.uagb-block-a8312775.uagb-marketing-btn__icon-after .uagb-marketing-btn__link svg{margin-left: 10px;}.uagb-block-a8312775.uagb-marketing-btn__icon-before .uagb-marketing-btn__link svg{margin-right: 10px;}.uagb-block-a8312775.uagb-marketing-btn__icon-after .uagb-marketing-btn__icon-wrap svg{margin-left: 10px;}.uagb-block-a8312775.uagb-marketing-btn__icon-before .uagb-marketing-btn__icon-wrap svg{margin-right: 10px;}.uagb-block-a8312775 .uagb-marketing-btn__title-wrap{align-items: center;}.uagb-block-a8312775 .uagb-marketing-btn__title-wrap .uagb-marketing-btn__icon-wrap svg{vertical-align: sub;}.uagb-block-a8312775 svg{width: 20px;height: 20px;}.uagb-block-a8312775 .uagb-marketing-btn__link.wp-block-button__link{border-color: var(u002du002dast-global-color-0);}.uagb-block-a8312775 .uagb-marketing-btn__wrap .uagb-marketing-btn__link{padding-left: 20px;padding-right: 20px;padding-top: 8px;padding-bottom: 8px;border-color: var(u002du002dast-global-color-0);}.uagb-block-a8312775 .uagb-marketing-btn__title{font-size: 15px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-kqaadqdx{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-kqaadqdx > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: flex-start;column-gap: 40px;}.wp-block-uagb-container.uagb-block-kqaadqdx{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(u002du002dast-global-color-5);;column-gap: 40px;}.uagb-block-6959b097.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6959b097.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-6959b097.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-6959b097 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-6959b097 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-6959b097 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-6959b097 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6959b097 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6959b097.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-6959b097.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-498bbe02 .uagb-toc__wrap{border-style: solid;}.uagb-block-498bbe02 .uagb-toc__list-wrap{column-count: 1;overflow: hidden;text-align: left;}.uagb-block-498bbe02 .uagb-toc__list-wrap > ul.uagb-toc__list > li:first-child{padding-top: 0;}.uagb-block-498bbe02 .uagb-toc__list-wrap ul.uagb-toc__list:last-child > li:last-child{padding-bottom: 0;}.uagb-block-18056ce0.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-18056ce0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-18056ce0.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-18056ce0 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-18056ce0 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-18056ce0 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-18056ce0 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-18056ce0 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-18056ce0 .uagb-ifb-content .uagb-ifb-image-content img{width: 100px;}.uagb-block-18056ce0.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 100px;}.uagb-block-18056ce0 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 100px;}.uagb-block-18056ce0 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 100px;}.uagb-block-18056ce0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-18056ce0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-c6fec501.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c6fec501.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-c6fec501.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c6fec501 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-c6fec501 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-c6fec501 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-c6fec501 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c6fec501 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c6fec501 .uagb-ifb-content .uagb-ifb-image-content img{width: 100px;}.uagb-block-c6fec501.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 100px;}.uagb-block-c6fec501 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 100px;}.uagb-block-c6fec501 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 100px;}.uagb-block-c6fec501.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-c6fec501.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-9021c5fa.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9021c5fa.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-9021c5fa.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-9021c5fa .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-9021c5fa .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-9021c5fa .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-9021c5fa .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9021c5fa .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9021c5fa .uagb-ifb-content .uagb-ifb-image-content img{width: 100px;}.uagb-block-9021c5fa.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 100px;}.uagb-block-9021c5fa .uagb-ifb-content .uagb-ifb-left-title-image img{width: 100px;}.uagb-block-9021c5fa .uagb-ifb-content .uagb-ifb-right-title-image img{width: 100px;}.uagb-block-9021c5fa.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-9021c5fa.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-697e79f9.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-697e79f9.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-697e79f9.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-697e79f9 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-697e79f9 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-697e79f9 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-697e79f9 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-697e79f9 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-697e79f9 .uagb-ifb-content .uagb-ifb-image-content img{width: 100px;}.uagb-block-697e79f9.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 100px;}.uagb-block-697e79f9 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 100px;}.uagb-block-697e79f9 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 100px;}.uagb-block-697e79f9.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-697e79f9.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-aba46c23.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-aba46c23.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-aba46c23.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-aba46c23 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-aba46c23 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-aba46c23 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-aba46c23 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-aba46c23 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-aba46c23 .uagb-ifb-content .uagb-ifb-image-content img{width: 100px;}.uagb-block-aba46c23.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 100px;}.uagb-block-aba46c23 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 100px;}.uagb-block-aba46c23 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 100px;}.uagb-block-aba46c23.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-aba46c23.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-e219a5cf.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e219a5cf.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-e219a5cf.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-e219a5cf .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-e219a5cf .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-e219a5cf .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-e219a5cf .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e219a5cf .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e219a5cf .uagb-ifb-content .uagb-ifb-image-content img{width: 100px;}.uagb-block-e219a5cf.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 100px;}.uagb-block-e219a5cf .uagb-ifb-content .uagb-ifb-left-title-image img{width: 100px;}.uagb-block-e219a5cf .uagb-ifb-content .uagb-ifb-right-title-image img{width: 100px;}.uagb-block-e219a5cf.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-e219a5cf.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-cb79a504.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cb79a504.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-cb79a504.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-cb79a504 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-cb79a504 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-cb79a504 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-cb79a504 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cb79a504 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cb79a504.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-cb79a504.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a560df08{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a560df08 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-a560df08{padding-top: 30px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-c0e7f988.uagb-social-share__layout-vertical .uagb-ss__wrapper{margin-left: 0;margin-right: 0;margin-top: 5px;margin-bottom: 5px;}.uagb-block-c0e7f988.uagb-social-share__layout-horizontal .uagb-ss__wrapper{margin-left: 5px;margin-right: 5px;}.uagb-block-c0e7f988.uagb-social-share__outer-wrap{justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: center;-ms-flex-align: center;align-items: center;}.uagb-block-a8312775 .uagb-marketing-btn__prefix{font-size: 14px;}.uagb-block-a8312775 .uagb-marketing-btn__link.wp-block-button__link{border-color: var(u002du002dast-global-color-0);}.uagb-block-a8312775 .uagb-marketing-btn__wrap .uagb-marketing-btn__link{padding-left: 20px;padding-right: 20px;padding-top: 8px;padding-bottom: 8px;border-color: var(u002du002dast-global-color-0);}.uagb-block-a8312775 .uagb-marketing-btn__title{font-size: 20px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-kqaadqdx{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-kqaadqdx > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-kqaadqdx{padding-top: 64px;padding-bottom: 64px;padding-left: 20px;padding-right: 20px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;order: initial;background-color: var(u002du002dast-global-color-5);;}.uagb-block-6959b097.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6959b097.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-6959b097 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6959b097 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6959b097.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-6959b097 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-6959b097 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-6959b097 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-6959b097.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-6959b097 .uagb-ifb-desc{font-size: 13px;}[dir=rtl] .uagb-block-6959b097.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-498bbe02 .uagb-toc__wrap{border-style: solid;}.uagb-block-498bbe02 .uagb-toc__list-wrap{column-count: 1;overflow: hidden;text-align: left;}.uagb-block-498bbe02 .uagb-toc__list-wrap > ul.uagb-toc__list > li:first-child{padding-top: 0;}.uagb-block-498bbe02 .uagb-toc__list-wrap ul.uagb-toc__list:last-child > li:last-child{padding-bottom: 0;}.uagb-block-18056ce0.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-18056ce0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-18056ce0 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-18056ce0 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-18056ce0.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-18056ce0 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-18056ce0 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-18056ce0 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-18056ce0 .uagb-ifb-content .uagb-ifb-image-content img{width: 100px;}.uagb-block-18056ce0.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 100px;}.uagb-block-18056ce0 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 100px;}.uagb-block-18056ce0 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 100px;}.uagb-block-18056ce0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-18056ce0 .uagb-ifb-desc{font-size: 13px;}[dir=rtl] .uagb-block-18056ce0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-c6fec501.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c6fec501.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-c6fec501 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c6fec501 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c6fec501.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c6fec501 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-c6fec501 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-c6fec501 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-c6fec501 .uagb-ifb-content .uagb-ifb-image-content img{width: 100px;}.uagb-block-c6fec501.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 100px;}.uagb-block-c6fec501 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 100px;}.uagb-block-c6fec501 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 100px;}.uagb-block-c6fec501.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-c6fec501 .uagb-ifb-desc{font-size: 13px;}[dir=rtl] .uagb-block-c6fec501.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-9021c5fa.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9021c5fa.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-9021c5fa .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9021c5fa .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9021c5fa.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-9021c5fa .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-9021c5fa .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-9021c5fa .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-9021c5fa .uagb-ifb-content .uagb-ifb-image-content img{width: 100px;}.uagb-block-9021c5fa.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 100px;}.uagb-block-9021c5fa .uagb-ifb-content .uagb-ifb-left-title-image img{width: 100px;}.uagb-block-9021c5fa .uagb-ifb-content .uagb-ifb-right-title-image img{width: 100px;}.uagb-block-9021c5fa.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-9021c5fa .uagb-ifb-desc{font-size: 13px;}[dir=rtl] .uagb-block-9021c5fa.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-697e79f9.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-697e79f9.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-697e79f9 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-697e79f9 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-697e79f9.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-697e79f9 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-697e79f9 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-697e79f9 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-697e79f9 .uagb-ifb-content .uagb-ifb-image-content img{width: 100px;}.uagb-block-697e79f9.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 100px;}.uagb-block-697e79f9 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 100px;}.uagb-block-697e79f9 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 100px;}.uagb-block-697e79f9.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-697e79f9 .uagb-ifb-desc{font-size: 13px;}[dir=rtl] .uagb-block-697e79f9.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-aba46c23.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-aba46c23.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-aba46c23 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-aba46c23 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-aba46c23.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-aba46c23 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-aba46c23 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-aba46c23 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-aba46c23 .uagb-ifb-content .uagb-ifb-image-content img{width: 100px;}.uagb-block-aba46c23.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 100px;}.uagb-block-aba46c23 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 100px;}.uagb-block-aba46c23 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 100px;}.uagb-block-aba46c23.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-aba46c23 .uagb-ifb-desc{font-size: 13px;}[dir=rtl] .uagb-block-aba46c23.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-e219a5cf.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e219a5cf.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-e219a5cf .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e219a5cf .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e219a5cf.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-e219a5cf .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-e219a5cf .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-e219a5cf .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-e219a5cf .uagb-ifb-content .uagb-ifb-image-content img{width: 100px;}.uagb-block-e219a5cf.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 100px;}.uagb-block-e219a5cf .uagb-ifb-content .uagb-ifb-left-title-image img{width: 100px;}.uagb-block-e219a5cf .uagb-ifb-content .uagb-ifb-right-title-image img{width: 100px;}.uagb-block-e219a5cf.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-e219a5cf .uagb-ifb-desc{font-size: 13px;}[dir=rtl] .uagb-block-e219a5cf.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-cb79a504.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cb79a504.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-cb79a504 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cb79a504 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cb79a504.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-cb79a504 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-cb79a504 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-cb79a504 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-cb79a504.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-cb79a504 .uagb-ifb-desc{font-size: 13px;}[dir=rtl] .uagb-block-cb79a504.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a560df08{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a560df08 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-a560df08{padding-top: 30px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-c0e7f988.uagb-social-share__layout-vertical .uagb-ss__wrapper{margin-left: 0;margin-right: 0;margin-top: 0px;margin-bottom: 0px;}.uagb-block-c0e7f988.uagb-social-share__layout-horizontal .uagb-ss__wrapper{margin-left: 0px;margin-right: 0px;}.uagb-block-c0e7f988.uagb-social-share__outer-wrap{justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: center;-ms-flex-align: center;align-items: center;}.uagb-block-a8312775 .uagb-marketing-btn__prefix{font-size: 14px;}.uagb-block-a8312775.wp-block-uagb-marketing-button.wp-block-button .uagb-marketing-btn__link{border-color: var(u002du002dast-global-color-0);}.uagb-block-a8312775 .uagb-marketing-btn__wrap .uagb-marketing-btn__link{padding-left: 20px;padding-right: 20px;padding-top: 8px;padding-bottom: 8px;border-color: var(u002du002dast-global-color-0);}.uagb-block-a8312775 .uagb-marketing-btn__title{font-size: 14px;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media (max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media (max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\n.uagb-block-e75f2e4c .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-e75f2e4c .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-e75f2e4c .uagb-ifb-icon svg{fill: #333;}.uagb-block-e75f2e4c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-e75f2e4c .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-e75f2e4c .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e75f2e4c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e75f2e4c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e75f2e4c .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-e75f2e4c .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-e75f2e4c .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e75f2e4c .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-e75f2e4c.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-e75f2e4c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-e75f2e4c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-e75f2e4c.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-e75f2e4c .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-e75f2e4c.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 10px;}.uagb-block-e75f2e4c.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-e75f2e4c .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-e75f2e4c .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-e75f2e4c .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-e75f2e4c .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-e75f2e4c.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-e75f2e4c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-e75f2e4c .uagb-infobox__content-wrap{text-align: left;}.uagb-block-e75f2e4c.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-e75f2e4c.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 15px;}.uagb-block-e75f2e4c.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 15px;}.uagb-block-e75f2e4c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-e75f2e4c .uagb-ifb-title{font-size: 20px;}[dir=rtl] .uagb-block-e75f2e4c .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e75f2e4c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e75f2e4c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e75f2e4c.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e75f2e4c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e75f2e4c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e75f2e4c.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e75f2e4c.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-e75f2e4c.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-e75f2e4c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.uagb-block-e75f2e4c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e75f2e4c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-e75f2e4c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-e75f2e4c .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-e75f2e4c .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-e75f2e4c .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-e75f2e4c .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e75f2e4c .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e75f2e4c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-e75f2e4c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-e75f2e4c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e75f2e4c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-e75f2e4c .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e75f2e4c .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e75f2e4c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-e75f2e4c .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-e75f2e4c .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-e75f2e4c .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-e75f2e4c.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-e75f2e4c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-e75f2e4c.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-e75f2e4c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.uagb-block-f10becaa .uagb-marketing-btn__prefix{font-size: 14px;line-height: 2em;margin-top: 0px;}.uagb-block-f10becaa.uagb-marketing-btn__icon-after .uagb-marketing-btn__link svg{margin-left: 10px;}.uagb-block-f10becaa.uagb-marketing-btn__icon-before .uagb-marketing-btn__link svg{margin-right: 10px;}.uagb-block-f10becaa.uagb-marketing-btn__icon-after .uagb-marketing-btn__icon-wrap svg{margin-left: 10px;}.uagb-block-f10becaa.uagb-marketing-btn__icon-before .uagb-marketing-btn__icon-wrap svg{margin-right: 10px;}.uagb-block-f10becaa .uagb-marketing-btn__title-wrap{align-items: center;}.uagb-block-f10becaa .uagb-marketing-btn__title-wrap .uagb-marketing-btn__icon-wrap svg{vertical-align: sub;}.uagb-block-f10becaa svg{width: 20px;height: 20px;}.uagb-block-f10becaa .uagb-marketing-btn__link.wp-block-button__link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: #333;border-style: solid;}.uagb-block-f10becaa .uagb-marketing-btn__wrap .uagb-marketing-btn__link{padding-left: 20px;padding-right: 20px;padding-top: 8px;padding-bottom: 8px;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: #333;border-style: solid;}.uagb-block-f10becaa .uagb-marketing-btn__title{font-size: 20px;}@media only screen and (max-width: 976px) {.uagb-block-f10becaa .uagb-marketing-btn__prefix{font-size: 14px;}.uagb-block-f10becaa .uagb-marketing-btn__link.wp-block-button__link{border-style: solid;border-color: #333;}.uagb-block-f10becaa .uagb-marketing-btn__wrap .uagb-marketing-btn__link{padding-left: 20px;padding-right: 20px;padding-top: 8px;padding-bottom: 8px;border-style: solid;border-color: #333;}.uagb-block-f10becaa .uagb-marketing-btn__title{font-size: 20px;}}@media only screen and (max-width: 767px) {.uagb-block-f10becaa .uagb-marketing-btn__prefix{font-size: 14px;}.uagb-block-f10becaa.wp-block-uagb-marketing-button.wp-block-button .uagb-marketing-btn__link{border-style: solid;border-color: #333;}.uagb-block-f10becaa .uagb-marketing-btn__wrap .uagb-marketing-btn__link{padding-left: 20px;padding-right: 20px;padding-top: 8px;padding-bottom: 8px;border-style: solid;border-color: #333;}.uagb-block-f10becaa .uagb-marketing-btn__title{font-size: 20px;}}.uagb-block-db23c273 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-db23c273 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: var(--ast-global-color-0);}.uagb-block-db23c273 .uagb-ifb-icon svg{fill: var(--ast-global-color-0);}.uagb-block-db23c273.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-db23c273 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-db23c273 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-db23c273.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-db23c273.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-db23c273 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-db23c273 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-db23c273 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-db23c273 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-db23c273.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-db23c273.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-db23c273.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-db23c273.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-db23c273 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-db23c273.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-db23c273.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-db23c273 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-db23c273 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-db23c273 .uagb-ifb-align-icon-after{margin-left: 12px;}.uagb-block-db23c273 .uagb-ifb-align-icon-before{margin-right: 12px;}.uagb-block-db23c273.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-db23c273.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-db23c273.uagb-infobox__content-wrap{border-style: none;}.uagb-block-db23c273 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-db23c273.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-db23c273.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 12px;}.uagb-block-db23c273 .uagb-infobox-cta-link svg{font-size: 15px;height: 15px;width: 15px;line-height: 15px;}.uagb-block-db23c273.wp-block-uagb-info-box .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link{color: var(--ast-global-color-0);background-color: var(--ast-global-color-5);}.uagb-block-db23c273.wp-block-uagb-info-box.uagb-infobox__content-wrap .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{color: var(--ast-global-color-0);background-color: var(--ast-global-color-5);border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: var(--ast-global-color-6);border-style: none;}.uagb-block-db23c273 .uagb-ifb-button-wrapper .uagb-infobox-cta-link svg{fill: var(--ast-global-color-0);}.uagb-block-db23c273.wp-block-uagb-info-box.uagb-infobox__content-wrap .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link:hover{color: var(--ast-global-color-5);background-color: var(--ast-global-color-0);border-color: var(--ast-global-color-0);}.uagb-block-db23c273 .uagb-infobox-cta-link:hover{border-color: var(--ast-global-color-0);}.uagb-block-db23c273 .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link:hover > svg{fill: var(--ast-global-color-5);}.uagb-block-db23c273.wp-block-uagb-info-box.uagb-infobox__content-wrap .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link:focus{color: var(--ast-global-color-5);background-color: var(--ast-global-color-0);border-color: var(--ast-global-color-0);}.uagb-block-db23c273 .uagb-infobox-cta-link:focus{border-color: var(--ast-global-color-0);}.uagb-block-db23c273 .uagb-infobox-cta-link{font-size: 15px;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: var(--ast-global-color-6);border-style: none;}[dir=rtl] .uagb-block-db23c273 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-db23c273.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-db23c273.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-db23c273.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-db23c273.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-db23c273.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-db23c273.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-db23c273.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-db23c273.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-db23c273.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 12px;margin-left: 0px;}@media only screen and (max-width: 976px) {.uagb-block-db23c273 .uagb-infobox-cta-link svg{font-size: 15px;height: 15px;width: 15px;line-height: 15px;}.uagb-block-db23c273.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-db23c273.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-db23c273.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-db23c273 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-db23c273 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-db23c273 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-db23c273 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-db23c273 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-db23c273.uagb-infobox__content-wrap{border-style: none;}.uagb-block-db23c273.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 12px;}.uagb-block-db23c273 .uagb-infobox-cta-link{border-style: none;border-color: var(--ast-global-color-6);}[dir=rtl] .uagb-block-db23c273.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 12px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-db23c273 .uagb-infobox-cta-link svg{font-size: 15px;height: 15px;width: 15px;line-height: 15px;}.uagb-block-db23c273.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-db23c273.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-db23c273 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-db23c273 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-db23c273.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-db23c273 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-db23c273 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-db23c273 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-db23c273.uagb-infobox__content-wrap{border-style: none;}.uagb-block-db23c273.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 12px;}.uagb-block-db23c273 .uagb-infobox-cta-link{border-style: none;border-color: var(--ast-global-color-6);}[dir=rtl] .uagb-block-db23c273.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 12px;margin-left: 0px;}}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-926e71b6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-926e71b6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-926e71b6{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-b250ee6e .uagb-ifb-icon svg{fill: #333;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-b250ee6e.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-6);margin-bottom: 0px;}.uagb-block-b250ee6e.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-6);margin-bottom: 0px;}.uagb-block-b250ee6e .uagb-ifb-separator{width: 99px;border-top-width: 1px;border-top-color: #ffffff;border-top-style: solid;margin-bottom: 5px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-b250ee6e .uagb-infobox__content-wrap .uagb-ifb-separator{width: 99px;border-top-width: 1px;border-top-color: #ffffff;border-top-style: solid;}.uagb-block-b250ee6e .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-infobox__content-wrap{text-align: left;}.uagb-block-b250ee6e.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-desc{font-size: 14px;}[dir=rtl] .uagb-block-b250ee6e .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-926e71b6{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-926e71b6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-926e71b6{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-926e71b6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-926e71b6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-926e71b6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-desc{font-size: 12px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-b250ee6e .uagb-ifb-icon svg{fill: #333;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-b250ee6e.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 10px;}.uagb-block-b250ee6e.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 20px;}.uagb-block-b250ee6e .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-b250ee6e .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-b250ee6e .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-infobox__content-wrap{text-align: left;}.uagb-block-b250ee6e.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-desc{font-size: 14px;}[dir=rtl] .uagb-block-b250ee6e .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-b250ee6e .uagb-ifb-icon svg{fill: #333;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-b250ee6e.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 10px;}.uagb-block-b250ee6e.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;}.uagb-block-b250ee6e .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-b250ee6e .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-b250ee6e .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-infobox__content-wrap{text-align: left;}.uagb-block-b250ee6e.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-desc{font-size: 14px;}[dir=rtl] .uagb-block-b250ee6e .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-b250ee6e .uagb-ifb-icon svg{fill: #333;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-b250ee6e.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;}.uagb-block-b250ee6e.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;}.uagb-block-b250ee6e .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-b250ee6e .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-b250ee6e .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-infobox__content-wrap{text-align: left;}.uagb-block-b250ee6e.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-desc{font-size: 14px;}[dir=rtl] .uagb-block-b250ee6e .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-b250ee6e .uagb-ifb-icon svg{fill: #333;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-b250ee6e.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-b250ee6e.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;}.uagb-block-b250ee6e .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-b250ee6e .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-b250ee6e .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-infobox__content-wrap{text-align: left;}.uagb-block-b250ee6e.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-desc{font-size: 14px;}[dir=rtl] .uagb-block-b250ee6e .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.wp-block-uagb-container.uagb-block-d0836f57 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d0836f57 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d0836f57 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d0836f57 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d0836f57 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d0836f57{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d0836f57 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-d0836f57{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-b250ee6e .uagb-ifb-icon svg{fill: #333;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-b250ee6e.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-6);margin-bottom: 0px;}.uagb-block-b250ee6e.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-6);margin-bottom: 0px;}.uagb-block-b250ee6e .uagb-ifb-separator{width: 60px;border-top-width: 1px;border-top-color: #ffffff;border-top-style: solid;margin-bottom: 5px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-b250ee6e .uagb-infobox__content-wrap .uagb-ifb-separator{width: 60px;border-top-width: 1px;border-top-color: #ffffff;border-top-style: solid;}.uagb-block-b250ee6e .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-infobox__content-wrap{text-align: left;}.uagb-block-b250ee6e.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-desc{font-size: 14px;}[dir=rtl] .uagb-block-b250ee6e .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-d0836f57{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d0836f57 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-d0836f57{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-d0836f57{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d0836f57 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-d0836f57{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-desc{font-size: 12px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.wp-block-uagb-container.uagb-block-ddec80c7 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ddec80c7 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ddec80c7 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ddec80c7 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ddec80c7 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ddec80c7{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ddec80c7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-ddec80c7{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 20px;}.uagb-block-edaec387 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-edaec387 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-edaec387 .uagb-ifb-icon svg{fill: #333;}.uagb-block-edaec387.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-edaec387 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-edaec387 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-edaec387.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-edaec387.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-edaec387 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-edaec387 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-edaec387 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-edaec387 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-edaec387.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-edaec387.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-edaec387.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-edaec387.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-edaec387 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-edaec387.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-6);margin-bottom: 0px;}.uagb-block-edaec387.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-6);margin-bottom: 20px;}.uagb-block-edaec387 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-edaec387 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-edaec387 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-edaec387 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-edaec387.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-edaec387.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-edaec387 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-edaec387.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-edaec387.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-edaec387 .uagb-ifb-title{font-family: \"League Spartan\";}.uagb-block-edaec387 .uagb-ifb-desc{font-size: 15px;}[dir=rtl] .uagb-block-edaec387 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-edaec387.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-edaec387.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-edaec387.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-edaec387.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-edaec387.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-edaec387.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-edaec387.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-edaec387.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-edaec387.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-ddec80c7{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ddec80c7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ddec80c7{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-edaec387.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-edaec387.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-edaec387.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-edaec387 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-edaec387 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-edaec387 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-edaec387 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-edaec387 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-edaec387.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-edaec387.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-ddec80c7{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ddec80c7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 0px;}.wp-block-uagb-container.uagb-block-ddec80c7{padding-top: 0px;padding-bottom: 30px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;row-gap: 0px;order: initial;}.uagb-block-edaec387.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-edaec387.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-edaec387 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-edaec387 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-edaec387.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-edaec387 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-edaec387 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-edaec387 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-edaec387.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-edaec387.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-edaec387 .uagb-ifb-desc{font-size: 12px;}[dir=rtl] .uagb-block-edaec387.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-edaec387.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-926e71b6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-926e71b6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-926e71b6{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 20px;}.uagb-block-ed6f73d6 .uagb-ifb-icon{width: 13px;line-height: 13px;}.uagb-block-ed6f73d6 .uagb-ifb-icon > span{font-size: 13px;width: 13px;line-height: 13px;color: var(--ast-global-color-5);}.uagb-block-ed6f73d6 .uagb-ifb-icon svg{fill: var(--ast-global-color-5);}.uagb-block-ed6f73d6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 13px;height: 13px;line-height: 13px;font-size: 13px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-ed6f73d6 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 13px;font-size: 13px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-ed6f73d6 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 13px;height: 13px;line-height: 13px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-ed6f73d6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-ed6f73d6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-ed6f73d6 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 13px;line-height: 13px;font-size: 13px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-ed6f73d6 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 13px;line-height: 13px;font-size: 13px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-ed6f73d6 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-ed6f73d6 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-ed6f73d6.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-ed6f73d6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-ed6f73d6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-ed6f73d6.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-ed6f73d6 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-ed6f73d6.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-6);margin-bottom: 0px;}.uagb-block-ed6f73d6.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-6);margin-bottom: 20px;}.uagb-block-ed6f73d6 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-ed6f73d6 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-ed6f73d6 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-ed6f73d6 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-ed6f73d6.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-ed6f73d6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ed6f73d6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-ed6f73d6 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ed6f73d6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ed6f73d6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ed6f73d6.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ed6f73d6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ed6f73d6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ed6f73d6.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ed6f73d6.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-ed6f73d6.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-ed6f73d6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 13px;line-height: 13px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 13px;width: 13px;line-height: 13px;color: var(--ast-global-color-5);}.uagb-block-b250ee6e .uagb-ifb-icon svg{fill: var(--ast-global-color-5);}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 13px;height: 13px;line-height: 13px;font-size: 13px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 13px;font-size: 13px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 13px;height: 13px;line-height: 13px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 13px;line-height: 13px;font-size: 13px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 13px;line-height: 13px;font-size: 13px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-b250ee6e .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-b250ee6e.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-6);margin-bottom: 0px;}.uagb-block-b250ee6e.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-6);margin-bottom: 0px;}.uagb-block-b250ee6e .uagb-ifb-separator{width: 95px;border-top-width: 1px;border-top-color: #ffffff;border-top-style: solid;margin-bottom: 5px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-b250ee6e .uagb-infobox__content-wrap .uagb-ifb-separator{width: 95px;border-top-width: 1px;border-top-color: #ffffff;border-top-style: solid;}.uagb-block-b250ee6e .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-desc{font-size: 14px;}[dir=rtl] .uagb-block-b250ee6e .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-926e71b6{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-926e71b6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-926e71b6{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-ed6f73d6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 13px;height: 13px;line-height: 13px;font-size: 13px;}.uagb-block-ed6f73d6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 13px;font-size: 13px;}.uagb-block-ed6f73d6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ed6f73d6 .uagb-ifb-icon{width: 13px;line-height: 13px;}.uagb-block-ed6f73d6 .uagb-ifb-icon > span{font-size: 13px;width: 13px;line-height: 13px;}.uagb-block-ed6f73d6 .uagb-iconbox-icon-wrap{width: 13px;height: 13px;line-height: 13px;}.uagb-block-ed6f73d6 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 13px;line-height: 13px;font-size: 13px;}.uagb-block-ed6f73d6 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 13px;line-height: 13px;font-size: 13px;}.uagb-block-ed6f73d6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-ed6f73d6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 13px;height: 13px;line-height: 13px;font-size: 13px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 13px;font-size: 13px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 13px;line-height: 13px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 13px;width: 13px;line-height: 13px;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{width: 13px;height: 13px;line-height: 13px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 13px;line-height: 13px;font-size: 13px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 13px;line-height: 13px;font-size: 13px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-926e71b6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-926e71b6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-926e71b6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-ed6f73d6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 13px;height: 13px;line-height: 13px;font-size: 13px;}.uagb-block-ed6f73d6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 13px;font-size: 13px;}.uagb-block-ed6f73d6 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 13px;line-height: 13px;font-size: 13px;}.uagb-block-ed6f73d6 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 13px;line-height: 13px;font-size: 13px;}.uagb-block-ed6f73d6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ed6f73d6 .uagb-ifb-icon{width: 13px;line-height: 13px;}.uagb-block-ed6f73d6 .uagb-ifb-icon > span{font-size: 13px;width: 13px;line-height: 13px;}.uagb-block-ed6f73d6 .uagb-iconbox-icon-wrap{width: 13px;height: 13px;line-height: 13px;}.uagb-block-ed6f73d6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-ed6f73d6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 13px;height: 13px;line-height: 13px;font-size: 13px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 13px;font-size: 13px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 13px;line-height: 13px;font-size: 13px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 13px;line-height: 13px;font-size: 13px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 13px;line-height: 13px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 13px;width: 13px;line-height: 13px;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{width: 13px;height: 13px;line-height: 13px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-desc{font-size: 12px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-926e71b6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-926e71b6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-926e71b6{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-b250ee6e .uagb-ifb-icon svg{fill: #333;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-b250ee6e.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 5px;}.uagb-block-b250ee6e.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;}.uagb-block-b250ee6e .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-b250ee6e .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-b250ee6e .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-infobox__content-wrap{text-align: left;}.uagb-block-b250ee6e.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-desc{font-size: 14px;}[dir=rtl] .uagb-block-b250ee6e .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-926e71b6{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-926e71b6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-926e71b6{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-926e71b6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-926e71b6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-926e71b6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-desc{font-size: 12px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-926e71b6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-926e71b6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-926e71b6{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-b250ee6e .uagb-ifb-icon svg{fill: #333;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-b250ee6e.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 5px;}.uagb-block-b250ee6e.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;}.uagb-block-b250ee6e .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-b250ee6e .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-b250ee6e .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-infobox__content-wrap{text-align: left;}.uagb-block-b250ee6e.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-desc{font-size: 14px;}[dir=rtl] .uagb-block-b250ee6e .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-926e71b6{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-926e71b6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-926e71b6{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-926e71b6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-926e71b6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-926e71b6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b250ee6e.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-desc{font-size: 12px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-926e71b6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-926e71b6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-926e71b6{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-b250ee6e .uagb-ifb-icon svg{fill: #333;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-b250ee6e.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 5px;}.uagb-block-b250ee6e.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;}.uagb-block-b250ee6e .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-b250ee6e .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-b250ee6e .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-infobox__content-wrap{text-align: left;}.uagb-block-b250ee6e.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-desc{font-size: 14px;}[dir=rtl] .uagb-block-b250ee6e .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-926e71b6{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-926e71b6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-926e71b6{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-926e71b6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-926e71b6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-926e71b6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b250ee6e.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-b250ee6e.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-desc{font-size: 12px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-926e71b6 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-926e71b6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-926e71b6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-926e71b6{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-b250ee6e .uagb-ifb-icon svg{fill: #333;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b250ee6e .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b250ee6e .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b250ee6e .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-b250ee6e.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 5px;}.uagb-block-b250ee6e.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;}.uagb-block-b250ee6e .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-b250ee6e .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-b250ee6e .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-infobox__content-wrap{text-align: left;}.uagb-block-b250ee6e.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-desc{font-size: 14px;}[dir=rtl] .uagb-block-b250ee6e .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-926e71b6{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-926e71b6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-926e71b6{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-926e71b6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-926e71b6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-926e71b6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b250ee6e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b250ee6e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b250ee6e.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-b250ee6e.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b250ee6e .uagb-ifb-desc{font-size: 12px;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-b250ee6e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.uagb-block-2a5b8029 .uagb-marketing-btn__prefix{font-size: 14px;line-height: 2em;margin-top: 0px;}.uagb-block-2a5b8029.uagb-marketing-btn__icon-after .uagb-marketing-btn__link svg{margin-left: 10px;}.uagb-block-2a5b8029.uagb-marketing-btn__icon-before .uagb-marketing-btn__link svg{margin-right: 10px;}.uagb-block-2a5b8029.uagb-marketing-btn__icon-after .uagb-marketing-btn__icon-wrap svg{margin-left: 10px;}.uagb-block-2a5b8029.uagb-marketing-btn__icon-before .uagb-marketing-btn__icon-wrap svg{margin-right: 10px;}.uagb-block-2a5b8029 .uagb-marketing-btn__title-wrap{align-items: center;}.uagb-block-2a5b8029 .uagb-marketing-btn__title-wrap .uagb-marketing-btn__icon-wrap svg{vertical-align: sub;}.uagb-block-2a5b8029 svg{width: 20px;height: 20px;}.uagb-block-2a5b8029 .uagb-marketing-btn__link svg{fill: #fff;}.uagb-block-2a5b8029 p.uagb-marketing-btn__prefix{color: #fff;}.uagb-block-2a5b8029 .uagb-marketing-btn__link.wp-block-button__link{padding-left: 35px;padding-right: 35px;padding-top: 10px;padding-bottom: 10px;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 100px;border-top-right-radius: 100px;border-bottom-left-radius: 100px;border-bottom-right-radius: 100px;border-color: #333;border-style: none;}.uagb-block-2a5b8029 .uagb-marketing-btn__wrap .uagb-marketing-btn__link{padding-left: 35px;padding-right: 35px;padding-top: 10px;padding-bottom: 10px;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 100px;border-top-right-radius: 100px;border-bottom-left-radius: 100px;border-bottom-right-radius: 100px;border-color: #333;border-style: none;}.uagb-block-2a5b8029 .uagb-marketing-btn__link .uagb-marketing-btn__title{color: #fff;}.uagb-block-2a5b8029 .uagb-marketing-btn__title{font-size: 20px;}@media only screen and (max-width: 976px) {.uagb-block-2a5b8029 .uagb-marketing-btn__prefix{font-size: 14px;}.uagb-block-2a5b8029 .uagb-marketing-btn__link.wp-block-button__link{border-style: none;border-color: #333;}.uagb-block-2a5b8029 .uagb-marketing-btn__wrap .uagb-marketing-btn__link{padding-left: 20px;padding-right: 20px;padding-top: 8px;padding-bottom: 8px;border-style: none;border-color: #333;}.uagb-block-2a5b8029 .uagb-marketing-btn__title{font-size: 20px;}}@media only screen and (max-width: 767px) {.uagb-block-2a5b8029 .uagb-marketing-btn__prefix{font-size: 14px;}.uagb-block-2a5b8029.wp-block-uagb-marketing-button.wp-block-button .uagb-marketing-btn__link{border-style: none;border-color: #333;}.uagb-block-2a5b8029 .uagb-marketing-btn__wrap .uagb-marketing-btn__link{padding-left: 20px;padding-right: 20px;padding-top: 8px;padding-bottom: 8px;border-style: none;border-color: #333;}.uagb-block-2a5b8029 .uagb-marketing-btn__title{font-size: 20px;}}.uagb-block-fe376bc9.wp-block-uagb-table-of-contents{text-align: left;}.uagb-block-fe376bc9 .uagb-toc__list-wrap li a{color: #54595F;}.uagb-block-fe376bc9 .uagb-toc__wrap .uagb-toc__title-wrap{justify-content: left;}.uagb-block-fe376bc9 .uagb-toc__wrap .uagb-toc__title{justify-content: left;}.uagb-block-fe376bc9 .uagb-toc__wrap{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-color: #333;border-style: solid;padding-left: 30px;padding-right: 30px;padding-top: 30px;padding-bottom: 30px;background: #fff;width: 100%;}.uagb-block-fe376bc9 .uagb-toc__list-wrap{column-count: 1;overflow: hidden;text-align: left;}.uagb-block-fe376bc9 .uagb-toc__list-wrap > ul.uagb-toc__list > li:first-child{padding-top: 0;}.uagb-block-fe376bc9 .uagb-toc__list-wrap ul.uagb-toc__list:last-child > li:last-child{padding-bottom: 0;}.uagb-block-fe376bc9 .uagb-toc__list .uagb-toc__list{list-style-type: disc !important;}.uagb-block-fe376bc9 .uagb-toc__title{font-weight: Default;font-size: 20px;}.uagb-block-fe376bc9 .uagb-toc__list-wrap ol li a{text-decoration: underline;}@media only screen and (max-width: 976px) {.uagb-block-fe376bc9 .uagb-toc__wrap{border-style: solid;}.uagb-block-fe376bc9 .uagb-toc__list-wrap{column-count: 1;overflow: hidden;text-align: left;}.uagb-block-fe376bc9 .uagb-toc__list-wrap > ul.uagb-toc__list > li:first-child{padding-top: 0;}.uagb-block-fe376bc9 .uagb-toc__list-wrap ul.uagb-toc__list:last-child > li:last-child{padding-bottom: 0;}}@media only screen and (max-width: 767px) {.uagb-block-fe376bc9 .uagb-toc__wrap{border-style: solid;}.uagb-block-fe376bc9 .uagb-toc__list-wrap{column-count: 1;overflow: hidden;text-align: left;}.uagb-block-fe376bc9 .uagb-toc__list-wrap > ul.uagb-toc__list > li:first-child{padding-top: 0;}.uagb-block-fe376bc9 .uagb-toc__list-wrap ul.uagb-toc__list:last-child > li:last-child{padding-bottom: 0;}}.wp-block-uagb-container.uagb-block-d3d6b90e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d3d6b90e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d3d6b90e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d3d6b90e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d3d6b90e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d3d6b90e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d3d6b90e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-d3d6b90e{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: ;;row-gap: 0px;column-gap: 0px;}.uagb-block-50d6a579 .uagb-ss-repeater span.uagb-ss__link{color: #ffffff;}.uagb-block-50d6a579 .uagb-ss-repeater a.uagb-ss__link{color: #ffffff;}.uagb-block-50d6a579 .uagb-ss-repeater span.uagb-ss__link svg{fill: #ffffff;}.uagb-block-50d6a579 .uagb-ss-repeater a.uagb-ss__link svg{fill: #ffffff;}.uagb-block-50d6a579 .uagb-ss-repeater.uagb-ss__wrapper{background: var(--ast-global-color-0);}.uagb-block-50d6a579.uagb-social-share__layout-vertical .uagb-ss__wrapper{margin-left: 0;margin-right: 0;margin-top: 7.5px;margin-bottom: 7.5px;}.uagb-block-50d6a579.uagb-social-share__layout-vertical .uagb-ss__link{padding: 12px;}.uagb-block-50d6a579.uagb-social-share__layout-horizontal .uagb-ss__link{padding: 12px;}.uagb-block-50d6a579.uagb-social-share__layout-horizontal .uagb-ss__wrapper{margin-left: 7.5px;margin-right: 7.5px;}.uagb-block-50d6a579 .wp-block-uagb-social-share-child {border-radius: 100px;}.uagb-block-50d6a579 .uagb-ss__source-wrap{width: 20px;}.uagb-block-50d6a579 .uagb-ss__source-wrap svg{width: 20px;height: 20px;}.uagb-block-50d6a579 .uagb-ss__source-image{width: 20px;}.uagb-block-50d6a579 .uagb-ss__source-icon{width: 20px;height: 20px;font-size: 20px;}.uagb-block-50d6a579.uagb-social-share__outer-wrap{justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: center;-ms-flex-align: center;align-items: center;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-d3d6b90e{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d3d6b90e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-d3d6b90e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: ;;}.uagb-block-50d6a579.uagb-social-share__layout-vertical .uagb-ss__wrapper{margin-left: 0;margin-right: 0;margin-top: 7.5px;margin-bottom: 7.5px;}.uagb-block-50d6a579.uagb-social-share__layout-horizontal .uagb-ss__wrapper{margin-left: 7.5px;margin-right: 7.5px;}.uagb-block-50d6a579 .wp-block-uagb-social-share-child {border-radius: 100px;}.uagb-block-50d6a579 .uagb-ss__source-wrap{width: 20px;height: 20px;line-height: 20px;}.uagb-block-50d6a579 .uagb-ss__source-wrap svg{width: 20px;height: 20px;}.uagb-block-50d6a579 .uagb-ss__source-image{width: 20px;}.uagb-block-50d6a579 .uagb-ss__source-icon{width: 20px;height: 20px;font-size: 20px;line-height: 20px;}.uagb-block-50d6a579.uagb-social-share__outer-wrap{justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: center;-ms-flex-align: center;align-items: center;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-d3d6b90e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d3d6b90e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-d3d6b90e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: ;;}.uagb-block-50d6a579.uagb-social-share__layout-vertical .uagb-ss__wrapper{margin-left: 0;margin-right: 0;margin-top: 7.5px;margin-bottom: 7.5px;}.uagb-block-50d6a579.uagb-social-share__layout-horizontal .uagb-ss__wrapper{margin-left: 7.5px;margin-right: 7.5px;}.uagb-block-50d6a579 .wp-block-uagb-social-share-child {border-radius: 100px;}.uagb-block-50d6a579 .uagb-ss__source-wrap{width: 20px;height: 20px;line-height: 20px;}.uagb-block-50d6a579 .uagb-ss__source-wrap svg{width: 20px;height: 20px;}.uagb-block-50d6a579 .uagb-ss__source-image{width: 20px;}.uagb-block-50d6a579 .uagb-ss__source-icon{width: 20px;height: 20px;font-size: 20px;line-height: 20px;}.uagb-block-50d6a579.uagb-social-share__outer-wrap{justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: center;-ms-flex-align: center;align-items: center;}}\";s:2:\"js\";s:2668:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener( 'load', function(){\n\tUAGBTableOfContents._run( {\"mappingHeaders\":[true,true,true,true,true,true],\"scrollToTop\":false,\"makeCollapsible\":false,\"enableCollapsableList\":false,\"initialCollapse\":false,\"markerView\":\"disc\",\"isFrontend\":true,\"initiallyCollapseList\":false}, '.uagb-block-498bbe02' );\n} );\nvar ssLinksParent = document.querySelector( '.uagb-block-c0e7f988' );\nssLinksParent?.addEventListener( 'keyup', function ( e ) {\nvar link = e.target.closest( '.uagb-ss__link' );\nif ( link && e.keyCode === 13 ) {\n\thandleSocialLinkClick( link );\n}\n});\n\nssLinksParent?.addEventListener( 'click', function ( e ) {\nvar link = e.target.closest( '.uagb-ss__link' );\nif ( link ) {\n\thandleSocialLinkClick( link );\n}\n});\n\nfunction handleSocialLinkClick( link ) {\nvar social_url = link.dataset.href;\nvar target = \"\";\nif ( social_url == \"mailto:?body=\" ) {\n\ttarget = \"_self\";\n}\nvar request_url = \"\";\nif ( social_url.indexOf(\"\/pin\/create\/link\/?url=\") !== -1 ) {\n\trequest_url = social_url + encodeURIComponent( window.location.href ) + \"&media=\" + 'https:\/\/noethera.com\/wp-content\/uploads\/2024\/11\/The-Ultimate-Guide-to-Optimizing-Your-Website-Budget-Without-Overpaying.jpg';\n} else {\n\trequest_url = social_url + encodeURIComponent( window.location.href );\n}\nwindow.open( request_url, target );\n}\nwindow.addEventListener( 'load', function(){\n\tUAGBTableOfContents._run( {\"mappingHeaders\":[true,true,true,true,true,true],\"scrollToTop\":false,\"makeCollapsible\":false,\"enableCollapsableList\":false,\"initialCollapse\":false,\"markerView\":\"disc\",\"isFrontend\":true,\"initiallyCollapseList\":false}, '.uagb-block-fe376bc9' );\n} );\nvar ssLinksParent = document.querySelector( '.uagb-block-50d6a579' );\nssLinksParent?.addEventListener( 'keyup', function ( e ) {\nvar link = e.target.closest( '.uagb-ss__link' );\nif ( link && e.keyCode === 13 ) {\n\thandleSocialLinkClick( link );\n}\n});\n\nssLinksParent?.addEventListener( 'click', function ( e ) {\nvar link = e.target.closest( '.uagb-ss__link' );\nif ( link ) {\n\thandleSocialLinkClick( link );\n}\n});\n\nfunction handleSocialLinkClick( link ) {\nvar social_url = link.dataset.href;\nvar target = \"\";\nif ( social_url == \"mailto:?body=\" ) {\n\ttarget = \"_self\";\n}\nvar request_url = \"\";\nif ( social_url.indexOf(\"\/pin\/create\/link\/?url=\") !== -1 ) {\n\trequest_url = social_url + encodeURIComponent( window.location.href ) + \"&media=\" + 'https:\/\/noethera.com\/wp-content\/uploads\/2024\/11\/The-Ultimate-Guide-to-Optimizing-Your-Website-Budget-Without-Overpaying.jpg';\n} else {\n\trequest_url = social_url + encodeURIComponent( window.location.href );\n}\nwindow.open( request_url, target );\n}\n });\";s:18:\"current_block_list\";a:24:{i:0;s:14:\"uagb\/container\";i:1;s:13:\"uagb\/info-box\";i:2;s:22:\"uagb\/table-of-contents\";i:3;s:9:\"core\/list\";i:4;s:14:\"core\/list-item\";i:5;s:11:\"core\/spacer\";i:7;s:12:\"core\/columns\";i:8;s:11:\"core\/column\";i:9;s:17:\"uagb\/social-share\";i:10;s:25:\"uagb\/animations-extension\";i:11;s:23:\"uagb\/social-share-child\";i:13;s:21:\"uagb\/marketing-button\";i:14;s:14:\"core\/paragraph\";i:15;s:11:\"core\/search\";i:16;s:10:\"core\/group\";i:17;s:12:\"core\/heading\";i:18;s:17:\"core\/latest-posts\";i:19;s:20:\"core\/latest-comments\";i:20;s:13:\"core\/archives\";i:21;s:15:\"core\/categories\";i:22;s:10:\"core\/image\";i:23;s:17:\"core\/social-links\";i:24;s:16:\"core\/social-link\";i:25;s:17:\"core\/widget-group\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1778499543\";s:6:\"gfonts\";a:1:{s:14:\"League Spartan\";a:2:{s:10:\"fontfamily\";s:14:\"League Spartan\";s:12:\"fontvariants\";a:0:{}}}s:10:\"gfonts_url\";s:84:\"https:\/\/fonts.googleapis.com\/css?family=League+Spartan&subset=latin&display=fallback\";s:12:\"gfonts_files\";a:1:{s:14:\"league-spartan\";s:133:\"https:\/\/noethera.com\/wp-content\/uploads\/uag-plugin\/assets\/fonts\/league-spartan\/kJEnBuEW6A0lliaV_m88ja5Twtx8BWhtkDVmjZvM_oTZA81d.woff2\";}s:14:\"uag_faq_layout\";b:0;}"],"_uag_css_file_name":["uag-css-7928.css"],"_uag_js_file_name":["uag-js-7928.js"]},"uagb_featured_image_src":{"full":["https:\/\/noethera.com\/wp-content\/uploads\/2024\/11\/The-Ultimate-Guide-to-Optimizing-Your-Website-Budget-Without-Overpaying.jpg",1000,667,false],"thumbnail":["https:\/\/noethera.com\/wp-content\/uploads\/2024\/11\/The-Ultimate-Guide-to-Optimizing-Your-Website-Budget-Without-Overpaying-150x150.jpg",150,150,true],"medium":["https:\/\/noethera.com\/wp-content\/uploads\/2024\/11\/The-Ultimate-Guide-to-Optimizing-Your-Website-Budget-Without-Overpaying-300x200.jpg",300,200,true],"medium_large":["https:\/\/noethera.com\/wp-content\/uploads\/2024\/11\/The-Ultimate-Guide-to-Optimizing-Your-Website-Budget-Without-Overpaying-768x512.jpg",768,512,true],"large":["https:\/\/noethera.com\/wp-content\/uploads\/2024\/11\/The-Ultimate-Guide-to-Optimizing-Your-Website-Budget-Without-Overpaying.jpg",1000,667,false],"1536x1536":["https:\/\/noethera.com\/wp-content\/uploads\/2024\/11\/The-Ultimate-Guide-to-Optimizing-Your-Website-Budget-Without-Overpaying.jpg",1000,667,false],"2048x2048":["https:\/\/noethera.com\/wp-content\/uploads\/2024\/11\/The-Ultimate-Guide-to-Optimizing-Your-Website-Budget-Without-Overpaying.jpg",1000,667,false],"trp-custom-language-flag":["https:\/\/noethera.com\/wp-content\/uploads\/2024\/11\/The-Ultimate-Guide-to-Optimizing-Your-Website-Budget-Without-Overpaying-18x12.jpg",18,12,true]},"uagb_author_info":{"display_name":"wirasetiawan29@gmail.com","author_link":"https:\/\/noethera.com\/id\/insight\/author\/wirasetiawan29gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"Learn how to optimize your website budget without overpaying. Get practical tips to balance cost, quality, and business needs for maximum value.","_links":{"self":[{"href":"https:\/\/noethera.com\/id\/wp-json\/wp\/v2\/posts\/7928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noethera.com\/id\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noethera.com\/id\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noethera.com\/id\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/noethera.com\/id\/wp-json\/wp\/v2\/comments?post=7928"}],"version-history":[{"count":2,"href":"https:\/\/noethera.com\/id\/wp-json\/wp\/v2\/posts\/7928\/revisions"}],"predecessor-version":[{"id":7930,"href":"https:\/\/noethera.com\/id\/wp-json\/wp\/v2\/posts\/7928\/revisions\/7930"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noethera.com\/id\/wp-json\/wp\/v2\/media\/7931"}],"wp:attachment":[{"href":"https:\/\/noethera.com\/id\/wp-json\/wp\/v2\/media?parent=7928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noethera.com\/id\/wp-json\/wp\/v2\/categories?post=7928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noethera.com\/id\/wp-json\/wp\/v2\/tags?post=7928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}